{"id":156153,"date":"2022-09-10T02:19:17","date_gmt":"2022-09-10T02:19:17","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Foods-Stress-Relief-coloring-page.jpg"},"modified":"2024-09-02T07:13:04","modified_gmt":"2024-09-02T07:13:04","slug":"lebensmittel-stressabbau","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/de\/erwachsene\/stressabbau\/attachment\/lebensmittel-stressabbau\/","title":{"rendered":"Lebensmittel Stressabbau"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-156153","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lebensmittel Stressabbau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/de\/erwachsene\/stressabbau\/attachment\/lebensmittel-stressabbau\/\" \/>\n<meta property=\"og:site_name\" content=\"Malvorlagen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-02T07:13:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/Foods-Stress-Relief-coloring-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"736\" \/>\n\t<meta property=\"og:image:height\" content=\"1033\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lebensmittel Stressabbau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_url":"https:\/\/coloringonly.com\/de\/erwachsene\/stressabbau\/attachment\/lebensmittel-stressabbau\/","og_site_name":"Malvorlagen","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-09-02T07:13:04+00:00","og_image":[{"width":736,"height":1033,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/Foods-Stress-Relief-coloring-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/de\/erwachsene\/stressabbau\/attachment\/lebensmittel-stressabbau\/","url":"https:\/\/coloringonly.com\/de\/erwachsene\/stressabbau\/attachment\/lebensmittel-stressabbau\/","name":"Lebensmittel Stressabbau Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/de\/#website"},"datePublished":"2022-09-10T02:19:17+00:00","dateModified":"2024-09-02T07:13:04+00:00","description":"Free printable Lebensmittel Stressabbau coloring page. You can download Lebensmittel Stressabbau coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/de\/erwachsene\/stressabbau\/attachment\/lebensmittel-stressabbau\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/de\/erwachsene\/stressabbau\/attachment\/lebensmittel-stressabbau\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/de\/erwachsene\/stressabbau\/attachment\/lebensmittel-stressabbau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/de\/"},{"@type":"ListItem","position":2,"name":"Erwachsene","item":"https:\/\/coloringonly.com\/de\/kategorie\/erwachsene\/"},{"@type":"ListItem","position":3,"name":"Stressabbau","item":"https:\/\/coloringonly.com\/de\/erwachsene\/stressabbau\/"},{"@type":"ListItem","position":4,"name":"Lebensmittel Stressabbau"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/de\/#website","url":"https:\/\/coloringonly.com\/de\/","name":"Coloring Pages","description":"Kostenlose Malvorlagen zum Ausdrucken f\u00fcr Kinder","publisher":{"@id":"https:\/\/coloringonly.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/de\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/Foods-Stress-Relief-coloring-page.jpg'><img decoding=\"async\" width=\"736\" height=\"1033\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/Foods-Stress-Relief-coloring-page.jpg\" class=\"attachment-medium size-medium\" alt=\"Stressabbau\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":736,"height":1033,"file":"Foods-Stress-Relief-coloring-page.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":232622},"post":156063,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Foods-Stress-Relief-coloring-page.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media\/156153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/comments?post=156153"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":156063,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/posts\/156063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}