{"id":172338,"date":"2021-09-06T01:26:18","date_gmt":"2021-09-06T01:26:18","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Cliff-Swallows-coloring-page.jpg"},"modified":"2024-08-22T08:32:11","modified_gmt":"2024-08-22T08:32:11","slug":"cliff-swallows","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/de\/tiere\/schlucken\/attachment\/cliff-swallows\/","title":{"rendered":"Klippenschwalben"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-172338","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klippenschwalben<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/de\/tiere\/schlucken\/attachment\/cliff-swallows\/\" \/>\n<meta property=\"og:site_name\" content=\"Malvorlagen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-22T08:32:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/Cliff-Swallows-coloring-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"718\" \/>\n\t<meta property=\"og:image:height\" content=\"957\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klippenschwalben","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_url":"https:\/\/coloringonly.com\/de\/tiere\/schlucken\/attachment\/cliff-swallows\/","og_site_name":"Malvorlagen","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-22T08:32:11+00:00","og_image":[{"width":718,"height":957,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/Cliff-Swallows-coloring-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/de\/tiere\/schlucken\/attachment\/cliff-swallows\/","url":"https:\/\/coloringonly.com\/de\/tiere\/schlucken\/attachment\/cliff-swallows\/","name":"Klippenschwalben Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/de\/#website"},"datePublished":"2021-09-06T01:26:18+00:00","dateModified":"2024-08-22T08:32:11+00:00","description":"Free printable Klippenschwalben coloring page. You can download Klippenschwalben coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/de\/tiere\/schlucken\/attachment\/cliff-swallows\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/de\/tiere\/schlucken\/attachment\/cliff-swallows\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/de\/tiere\/schlucken\/attachment\/cliff-swallows\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/de\/"},{"@type":"ListItem","position":2,"name":"Tiere","item":"https:\/\/coloringonly.com\/de\/kategorie\/tiere\/"},{"@type":"ListItem","position":3,"name":"Schwalbe","item":"https:\/\/coloringonly.com\/de\/animals\/swallow\/"},{"@type":"ListItem","position":4,"name":"Klippenschwalben"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/de\/#website","url":"https:\/\/coloringonly.com\/de\/","name":"Coloring Pages","description":"Kostenlose Malvorlagen zum Ausdrucken f\u00fcr Kinder","publisher":{"@id":"https:\/\/coloringonly.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/de\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/Cliff-Swallows-coloring-page.jpg'><img decoding=\"async\" width=\"718\" height=\"957\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/Cliff-Swallows-coloring-page.jpg\" class=\"attachment-medium size-medium\" alt=\"Schwalbe\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":718,"height":957,"file":"Cliff-Swallows-coloring-page.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":171877,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Cliff-Swallows-coloring-page.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media\/172338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/comments?post=172338"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":171877,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/posts\/171877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}