{"id":207852,"date":"2023-12-04T12:35:48","date_gmt":"2023-12-04T12:35:48","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/christmas-bells-08.png"},"modified":"2024-06-12T07:13:00","modified_gmt":"2024-06-12T07:13:00","slug":"einfach-ausdruckbare-weihnachten-zwei-niedliche-glocken","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/de\/feiertage\/weihnachtsglocken\/attachment\/einfach-ausdruckbare-weihnachten-zwei-niedliche-glocken\/","title":{"rendered":"Einfach ausdruckbare Weihnachten Zwei niedliche Glocken"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-207852","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Einfach ausdruckbare Weihnachten Zwei niedliche Glocken<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/de\/feiertage\/weihnachtsglocken\/attachment\/einfach-ausdruckbare-weihnachten-zwei-niedliche-glocken\/\" \/>\n<meta property=\"og:site_name\" content=\"Malvorlagen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T07:13:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/easy-printable-christmas-two-cute-bells-coloring-pages.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einfach ausdruckbare Weihnachten Zwei niedliche Glocken","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_url":"https:\/\/coloringonly.com\/de\/feiertage\/weihnachtsglocken\/attachment\/einfach-ausdruckbare-weihnachten-zwei-niedliche-glocken\/","og_site_name":"Malvorlagen","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-06-12T07:13:00+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/easy-printable-christmas-two-cute-bells-coloring-pages.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/de\/feiertage\/weihnachtsglocken\/attachment\/einfach-ausdruckbare-weihnachten-zwei-niedliche-glocken\/","url":"https:\/\/coloringonly.com\/de\/feiertage\/weihnachtsglocken\/attachment\/einfach-ausdruckbare-weihnachten-zwei-niedliche-glocken\/","name":"Einfach ausdruckbare Weihnachten Zwei niedliche Glocken Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/de\/#website"},"datePublished":"2023-12-04T12:35:48+00:00","dateModified":"2024-06-12T07:13:00+00:00","description":"Free printable Einfach ausdruckbare Weihnachten Zwei niedliche Glocken coloring page. You can download Einfach ausdruckbare Weihnachten Zwei niedliche Glocken coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/de\/feiertage\/weihnachtsglocken\/attachment\/einfach-ausdruckbare-weihnachten-zwei-niedliche-glocken\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/de\/feiertage\/weihnachtsglocken\/attachment\/einfach-ausdruckbare-weihnachten-zwei-niedliche-glocken\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/de\/feiertage\/weihnachtsglocken\/attachment\/einfach-ausdruckbare-weihnachten-zwei-niedliche-glocken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/de\/"},{"@type":"ListItem","position":2,"name":"Feiertage","item":"https:\/\/coloringonly.com\/de\/kategorie\/feiertage\/"},{"@type":"ListItem","position":3,"name":"Weihnachtsglocken","item":"https:\/\/coloringonly.com\/de\/feiertage\/weihnachtsglocken\/"},{"@type":"ListItem","position":4,"name":"Einfach ausdruckbare Weihnachten Zwei niedliche Glocken"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/de\/#website","url":"https:\/\/coloringonly.com\/de\/","name":"Coloring Pages","description":"Kostenlose Malvorlagen zum Ausdrucken f\u00fcr Kinder","publisher":{"@id":"https:\/\/coloringonly.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/de\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/.\/easy-printable-christmas-two-cute-bells-coloring-pages.png'><img decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/christmas-bells-08-225x300.png\" class=\"attachment-medium size-medium\" alt=\"Einfach ausdruckbare Ausmalbilder Weihnachten Zwei Niedliche Glocken\" srcset=\"https:\/\/coloringonly.com\/images\/imgcolor\/christmas-bells-08-225x300.png 225w, https:\/\/coloringonly.com\/images\/imgcolor\/christmas-bells-08-113x150.png 113w, https:\/\/coloringonly.com\/images\/imgcolor\/christmas-bells-08-150x200.png 150w, https:\/\/coloringonly.com\/images\/imgcolor\/christmas-bells-08.png 600w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Einfach ausdruckbare Ausmalbilder Weihnachten Zwei Niedliche Glocken<\/p>\n"},"caption":{"rendered":"<p>Einfach ausdruckbare Ausmalbilder Weihnachten Zwei Niedliche Glocken<\/p>\n"},"alt_text":"Einfach ausdruckbare Ausmalbilder Weihnachten Zwei Niedliche Glocken","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":800,"file":"christmas-bells-08.png","filesize":57338,"sizes":{"medium":{"file":"christmas-bells-08-225x300.png","width":225,"height":300,"filesize":21258,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/christmas-bells-08-225x300.png"},"thumbnail":{"file":"christmas-bells-08-113x150.png","width":113,"height":150,"filesize":7526,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/christmas-bells-08-113x150.png"},"web-stories-publisher-logo":{"file":"christmas-bells-08-96x96.png","width":96,"height":96,"filesize":4808,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/christmas-bells-08-96x96.png"},"web-stories-thumbnail":{"file":"christmas-bells-08-150x200.png","width":150,"height":200,"filesize":11880,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/christmas-bells-08-150x200.png"},"full":{"file":"easy-printable-christmas-two-cute-bells-coloring-pages.png","width":600,"height":800,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/easy-printable-christmas-two-cute-bells-coloring-pages.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":208088,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/easy-printable-christmas-two-cute-bells-coloring-pages.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media\/207852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/comments?post=207852"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":208088,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/posts\/208088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}