{"id":213719,"date":"2024-02-29T17:34:12","date_gmt":"2024-02-29T17:34:12","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Flower-Coloring-Pages-for-Adults-01.png"},"modified":"2025-10-08T14:17:46","modified_gmt":"2025-10-08T14:17:46","slug":"flower-coloring-pages-for-adults-01-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/de\/blumen-und-pflanzen\/blume-fuer-erwachsene\/attachment\/flower-coloring-pages-for-adults-01-2\/","title":{"rendered":"Komplizierte Blumen in einer Vase"},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-213719","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Komplizierte Blumen in einer Vase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/de\/blumen-und-pflanzen\/blume-fuer-erwachsene\/attachment\/flower-coloring-pages-for-adults-01-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Malvorlagen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T14:17:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/complicated-flowers-in-a-vase-coloring-page.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Komplizierte Blumen in einer Vase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_url":"https:\/\/coloringonly.com\/de\/blumen-und-pflanzen\/blume-fuer-erwachsene\/attachment\/flower-coloring-pages-for-adults-01-2\/","og_site_name":"Malvorlagen","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2025-10-08T14:17:46+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/complicated-flowers-in-a-vase-coloring-page.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/de\/blumen-und-pflanzen\/blume-fuer-erwachsene\/attachment\/flower-coloring-pages-for-adults-01-2\/","url":"https:\/\/coloringonly.com\/de\/blumen-und-pflanzen\/blume-fuer-erwachsene\/attachment\/flower-coloring-pages-for-adults-01-2\/","name":"Komplizierte Blumen in einer Vase Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/de\/#website"},"datePublished":"2024-02-29T17:34:12+00:00","dateModified":"2025-10-08T14:17:46+00:00","description":"Free printable Komplizierte Blumen in einer Vase coloring page. You can download Komplizierte Blumen in einer Vase coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/de\/blumen-und-pflanzen\/blume-fuer-erwachsene\/attachment\/flower-coloring-pages-for-adults-01-2\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/de\/blumen-und-pflanzen\/blume-fuer-erwachsene\/attachment\/flower-coloring-pages-for-adults-01-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/de\/blumen-und-pflanzen\/blume-fuer-erwachsene\/attachment\/flower-coloring-pages-for-adults-01-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/de\/"},{"@type":"ListItem","position":2,"name":"Blumen und Pflanzen","item":"https:\/\/coloringonly.com\/de\/kategorie\/blumen-und-pflanzen\/"},{"@type":"ListItem","position":3,"name":"Blume f\u00fcr Erwachsene","item":"https:\/\/coloringonly.com\/de\/blumen-und-pflanzen\/blume-fuer-erwachsene\/"},{"@type":"ListItem","position":4,"name":"Komplizierte Blumen in einer Vase"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/de\/#website","url":"https:\/\/coloringonly.com\/de\/","name":"Coloring Pages","description":"Kostenlose Malvorlagen zum Ausdrucken f\u00fcr Kinder","publisher":{"@id":"https:\/\/coloringonly.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/de\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/.\/complicated-flowers-in-a-vase-coloring-page.png'><img decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/complicated-flowers-in-a-vase-coloring-page.png\" class=\"attachment-medium size-medium\" alt=\"Komplizierte Blumen in einer Vase Malvorlage\" \/><\/a><\/p>\n<p>Komplizierte Blumen in einer Vase Malvorlage<\/p>\n"},"caption":{"rendered":"<p>Komplizierte Blumen in einer Vase Malvorlage<\/p>\n"},"alt_text":"Komplizierte Blumen in einer Vase Malvorlage","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":800,"file":"Flower-Coloring-Pages-for-Adults-01.png","filesize":119234,"sizes":{"web-stories-publisher-logo":{"file":"Flower-Coloring-Pages-for-Adults-01-96x96.png","width":96,"height":96,"filesize":5262,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/Flower-Coloring-Pages-for-Adults-01-96x96.png"},"web-stories-thumbnail":{"file":"Flower-Coloring-Pages-for-Adults-01-150x200.png","width":150,"height":200,"filesize":12599,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/Flower-Coloring-Pages-for-Adults-01-150x200.png"},"full":{"file":"complicated-flowers-in-a-vase-coloring-page.png","width":600,"height":800,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/complicated-flowers-in-a-vase-coloring-page.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":214419,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/complicated-flowers-in-a-vase-coloring-page.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media\/213719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/comments?post=213719"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":214419,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/posts\/214419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}