{"id":336429,"date":"2025-04-22T13:07:03","date_gmt":"2025-04-22T13:07:03","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Labubu-Doll-Coloring-Page-01.png"},"modified":"2025-10-08T12:20:10","modified_gmt":"2025-10-08T12:20:10","slug":"labubu-doll-coloring-page-01-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/de\/spielzeuge-puppen\/labubu-coloring-page\/attachment\/labubu-doll-coloring-page-01-2\/","title":{"rendered":"Labubu Puppe"},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-336429","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Labubu Puppe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/de\/spielzeuge-puppen\/labubu-coloring-page\/attachment\/labubu-doll-coloring-page-01-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Malvorlagen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T12:20:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/labubu-doll-coloring-page.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Labubu Puppe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_url":"https:\/\/coloringonly.com\/de\/spielzeuge-puppen\/labubu-coloring-page\/attachment\/labubu-doll-coloring-page-01-2\/","og_site_name":"Malvorlagen","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2025-10-08T12:20:10+00:00","og_image":[{"width":800,"height":1000,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/labubu-doll-coloring-page.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/de\/spielzeuge-puppen\/labubu-coloring-page\/attachment\/labubu-doll-coloring-page-01-2\/","url":"https:\/\/coloringonly.com\/de\/spielzeuge-puppen\/labubu-coloring-page\/attachment\/labubu-doll-coloring-page-01-2\/","name":"Labubu Puppe Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/de\/#website"},"datePublished":"2025-04-22T13:07:03+00:00","dateModified":"2025-10-08T12:20:10+00:00","description":"Free printable Labubu Puppe coloring page. You can download Labubu Puppe coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/de\/spielzeuge-puppen\/labubu-coloring-page\/attachment\/labubu-doll-coloring-page-01-2\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/de\/spielzeuge-puppen\/labubu-coloring-page\/attachment\/labubu-doll-coloring-page-01-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/de\/spielzeuge-puppen\/labubu-coloring-page\/attachment\/labubu-doll-coloring-page-01-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/de\/"},{"@type":"ListItem","position":2,"name":"Spielzeuge &amp; Puppen","item":"https:\/\/coloringonly.com\/de\/kategorie\/spielzeuge-puppen\/"},{"@type":"ListItem","position":3,"name":"Labubu","item":"https:\/\/coloringonly.com\/de\/spielzeuge-puppen\/labubu-coloring-page\/"},{"@type":"ListItem","position":4,"name":"Labubu Puppe"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/de\/#website","url":"https:\/\/coloringonly.com\/de\/","name":"Coloring Pages","description":"Kostenlose Malvorlagen zum Ausdrucken f\u00fcr Kinder","publisher":{"@id":"https:\/\/coloringonly.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/de\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/.\/labubu-doll-coloring-page.png'><img decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/labubu-doll-coloring-page.png\" class=\"attachment-medium size-medium\" alt=\"Ausmalbild Labubu Puppe\" \/><\/a><\/p>\n<p>Ausmalbild Labubu Puppe<\/p>\n"},"caption":{"rendered":"<p>Ausmalbild Labubu Puppe<\/p>\n"},"alt_text":"Ausmalbild Labubu Puppe","media_type":"image","mime_type":"image\/png","media_details":{"width":800,"height":1000,"file":"Labubu-Doll-Coloring-Page-01.png","filesize":75974,"sizes":{"medium_large":{"file":"Labubu-Doll-Coloring-Page-01-768x960.png","width":768,"height":960,"filesize":86164,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/Labubu-Doll-Coloring-Page-01-768x960.png"},"full":{"file":"labubu-doll-coloring-page.png","width":800,"height":1000,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/labubu-doll-coloring-page.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":337539,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/labubu-doll-coloring-page.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media\/336429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/comments?post=336429"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":337539,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/posts\/337539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}