{"id":95605,"date":"2020-09-12T00:26:56","date_gmt":"2020-09-12T00:26:56","guid":{"rendered":"https:\/\/helppdf.com\/images\/imgcolor\/1594862411_toppng.com-oku-coloring-games-son-by-coloring-page-goku-super-dragon-ball-para-colorear-gogeta-ssj5-827x959-1.jpg"},"modified":"2024-06-11T07:48:52","modified_gmt":"2024-06-11T07:48:52","slug":"glucklicher-ssj4-gogeta-fighting","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/de\/anime-de\/dragon-ball\/attachment\/glucklicher-ssj4-gogeta-fighting\/","title":{"rendered":"Gl\u00fccklicher SSJ4 Gogeta Fighting"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-95605","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gl\u00fccklicher SSJ4 Gogeta Fighting<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/de\/anime-de\/dragon-ball\/attachment\/glucklicher-ssj4-gogeta-fighting\/\" \/>\n<meta property=\"og:site_name\" content=\"Malvorlagen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T07:48:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/1594862411_toppng.com-oku-coloring-games-son-by-coloring-page-goku-super-dragon-ball-para-colorear-gogeta-ssj5-827x959-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"736\" \/>\n\t<meta property=\"og:image:height\" content=\"950\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gl\u00fccklicher SSJ4 Gogeta Fighting","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_url":"https:\/\/coloringonly.com\/de\/anime-de\/dragon-ball\/attachment\/glucklicher-ssj4-gogeta-fighting\/","og_site_name":"Malvorlagen","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-06-11T07:48:52+00:00","og_image":[{"width":736,"height":950,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/1594862411_toppng.com-oku-coloring-games-son-by-coloring-page-goku-super-dragon-ball-para-colorear-gogeta-ssj5-827x959-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/de\/anime-de\/dragon-ball\/attachment\/glucklicher-ssj4-gogeta-fighting\/","url":"https:\/\/coloringonly.com\/de\/anime-de\/dragon-ball\/attachment\/glucklicher-ssj4-gogeta-fighting\/","name":"Gl\u00fccklicher SSJ4 Gogeta Fighting Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/de\/#website"},"datePublished":"2020-09-12T00:26:56+00:00","dateModified":"2024-06-11T07:48:52+00:00","description":"Free printable Gl\u00fccklicher SSJ4 Gogeta Fighting coloring page. You can download Gl\u00fccklicher SSJ4 Gogeta Fighting coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/de\/anime-de\/dragon-ball\/attachment\/glucklicher-ssj4-gogeta-fighting\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/de\/anime-de\/dragon-ball\/attachment\/glucklicher-ssj4-gogeta-fighting\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/de\/anime-de\/dragon-ball\/attachment\/glucklicher-ssj4-gogeta-fighting\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/de\/"},{"@type":"ListItem","position":2,"name":"Anime","item":"https:\/\/coloringonly.com\/de\/kategorie\/anime-de\/"},{"@type":"ListItem","position":3,"name":"Dragon Ball","item":"https:\/\/coloringonly.com\/de\/anime-de\/dragon-ball\/"},{"@type":"ListItem","position":4,"name":"Gl\u00fccklicher SSJ4 Gogeta Fighting"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/de\/#website","url":"https:\/\/coloringonly.com\/de\/","name":"Coloring Pages","description":"Kostenlose Malvorlagen zum Ausdrucken f\u00fcr Kinder","publisher":{"@id":"https:\/\/coloringonly.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/de\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/1594862411_toppng.com-oku-coloring-games-son-by-coloring-page-goku-super-dragon-ball-para-colorear-gogeta-ssj5-827x959-1.jpg'><img decoding=\"async\" width=\"736\" height=\"950\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/1594862411_toppng.com-oku-coloring-games-son-by-coloring-page-goku-super-dragon-ball-para-colorear-gogeta-ssj5-827x959-1.jpg\" class=\"attachment-medium size-medium\" alt=\"Dragon Ball\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":736,"height":950,"file":"1594862411_toppng.com-oku-coloring-games-son-by-coloring-page-goku-super-dragon-ball-para-colorear-gogeta-ssj5-827x959-1.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":118058},"post":137657,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/1594862411_toppng.com-oku-coloring-games-son-by-coloring-page-goku-super-dragon-ball-para-colorear-gogeta-ssj5-827x959-1.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media\/95605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/comments?post=95605"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":137657,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/posts\/137657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}