{"id":139558,"date":"2020-09-16T00:20:57","date_gmt":"2020-09-16T00:20:57","guid":{"rendered":"https:\/\/coloringonly.com\/unkategorisiert\/bulma-2\/"},"modified":"2024-06-11T09:47:55","modified_gmt":"2024-06-11T09:47:55","slug":"bulma-2","status":"publish","type":"post","link":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/","title":{"rendered":"Bulma"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":92430,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[354],"tags":[],"class_list":["post-139558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anime-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bulma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Malvorlagen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-16T00:20:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T09:47:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/1551082561_50b74c9dfd4c022824657b89549c38cd.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"3400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Oren_landocs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ColoringO\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Oren_landocs\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bulma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_url":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/","og_site_name":"Malvorlagen","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_published_time":"2020-09-16T00:20:57+00:00","article_modified_time":"2024-06-11T09:47:55+00:00","og_image":[{"width":2400,"height":3400,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/1551082561_50b74c9dfd4c022824657b89549c38cd.gif","type":"image\/gif"}],"author":"Oren_landocs","twitter_card":"summary_large_image","twitter_creator":"@ColoringO","twitter_site":"@ColoringO","twitter_misc":{"Written by":"Oren_landocs"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/#article","isPartOf":{"@id":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/"},"author":{"name":"Oren_landocs","@id":"https:\/\/coloringonly.com\/de\/#\/schema\/person\/0392a423d93935b9764dd3f915ad667f"},"headline":"Bulma","datePublished":"2020-09-16T00:20:57+00:00","dateModified":"2024-06-11T09:47:55+00:00","mainEntityOfPage":{"@id":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/"},"wordCount":1,"commentCount":0,"publisher":{"@id":"https:\/\/coloringonly.com\/de\/#organization"},"image":{"@id":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/#primaryimage"},"thumbnailUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/1551082561_50b74c9dfd4c022824657b89549c38cd.gif","articleSection":["Anime"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/","url":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/","name":"Bulma Malvorlagen - Kostenlose druckbare Malvorlagen f\u00fcr Kinder","isPartOf":{"@id":"https:\/\/coloringonly.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/#primaryimage"},"image":{"@id":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/#primaryimage"},"thumbnailUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/1551082561_50b74c9dfd4c022824657b89549c38cd.gif","datePublished":"2020-09-16T00:20:57+00:00","dateModified":"2024-06-11T09:47:55+00:00","description":"Bulma coloring pages. You can download free printable Bulma coloring pages at Coloringonly.com. We have selected the best Bulma coloring pages that you can download online on mobile, tablet... for free and add new coloring pages daily, enjoy!","breadcrumb":{"@id":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/#primaryimage","url":"https:\/\/coloringonly.com\/images\/imgcolor\/1551082561_50b74c9dfd4c022824657b89549c38cd.gif","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/1551082561_50b74c9dfd4c022824657b89549c38cd.gif","width":2400,"height":3400},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/de\/anime-de\/bulma-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/de\/"},{"@type":"ListItem","position":2,"name":"Anime","item":"https:\/\/coloringonly.com\/de\/kategorie\/anime-de\/"},{"@type":"ListItem","position":3,"name":"Bulma"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/de\/#website","url":"https:\/\/coloringonly.com\/de\/","name":"Coloring Pages","description":"Kostenlose Malvorlagen zum Ausdrucken f\u00fcr Kinder","publisher":{"@id":"https:\/\/coloringonly.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/de\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]},{"@type":"Person","@id":"https:\/\/coloringonly.com\/de\/#\/schema\/person\/0392a423d93935b9764dd3f915ad667f","name":"Oren_landocs","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/f2b9440c35e45069afaadd70d999defdb675eb79203bdaebc00f3804dc9bfdaf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f2b9440c35e45069afaadd70d999defdb675eb79203bdaebc00f3804dc9bfdaf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2b9440c35e45069afaadd70d999defdb675eb79203bdaebc00f3804dc9bfdaf?s=96&d=mm&r=g","caption":"Oren_landocs"}}]}},"_links":{"self":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/posts\/139558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/comments?post=139558"}],"version-history":[{"count":0,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/posts\/139558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media\/92430"}],"wp:attachment":[{"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/media?parent=139558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/categories?post=139558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coloringonly.com\/de\/wp-json\/wp\/v2\/tags?post=139558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}