{"id":34188,"date":"2021-10-12T08:20:40","date_gmt":"2021-10-12T08:20:40","guid":{"rendered":"https:\/\/dibujos-colorear.com\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg"},"modified":"2021-10-12T08:20:40","modified_gmt":"2021-10-12T08:20:40","slug":"lindo-camion-de-basura","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/es\/pages\/lindo-camion-de-basura\/","title":{"rendered":"Lindo Cami\u00f3n de Basura"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-34188","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lindo Cami\u00f3n de Basura para colorear, imprimir e dibujar \u2013ColoringOnly.Com<\/title>\n<meta name=\"description\" content=\"Puede descargar una p\u00e1gina para Lindo Cami\u00f3n de Basura colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lindo Cami\u00f3n de Basura para colorear, imprimir e dibujar \u2013ColoringOnly.Com\" \/>\n<meta property=\"og:description\" content=\"Puede descargar una p\u00e1gina para Lindo Cami\u00f3n de Basura colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Coloringonly.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"473\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Lindo-Cami\u00f3n-de-Basura.jpg\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Lindo-Cami\u00f3n-de-Basura.jpg\",\"name\":\"Lindo Cami\u00f3n de Basura para colorear, imprimir e dibujar \u2013ColoringOnly.Com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\"},\"datePublished\":\"2021-10-12T08:20:40+00:00\",\"description\":\"Puede descargar una p\u00e1gina para Lindo Cami\u00f3n de Basura colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Lindo-Cami\u00f3n-de-Basura.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Lindo-Cami\u00f3n-de-Basura.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Lindo-Cami\u00f3n-de-Basura.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veh\u00edculos\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/cat\\\/vehiculos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cami\u00f3n De La Basura\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/camion-de-la-basura\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Lindo Cami\u00f3n de Basura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\",\"name\":\"Coloringonly.com\",\"description\":\"Free Printable Coloring Pages for Kids\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lindo Cami\u00f3n de Basura para colorear, imprimir e dibujar \u2013ColoringOnly.Com","description":"Puede descargar una p\u00e1gina para Lindo Cami\u00f3n de Basura colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg","og_locale":"en_US","og_type":"article","og_title":"Lindo Cami\u00f3n de Basura para colorear, imprimir e dibujar \u2013ColoringOnly.Com","og_description":"Puede descargar una p\u00e1gina para Lindo Cami\u00f3n de Basura colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","og_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg","og_site_name":"Coloringonly.com","og_image":[{"width":512,"height":473,"url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg","url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg","name":"Lindo Cami\u00f3n de Basura para colorear, imprimir e dibujar \u2013ColoringOnly.Com","isPartOf":{"@id":"https:\/\/coloringonly.com\/es\/#website"},"datePublished":"2021-10-12T08:20:40+00:00","description":"Puede descargar una p\u00e1gina para Lindo Cami\u00f3n de Basura colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coloringonly.com\/es\/"},{"@type":"ListItem","position":2,"name":"Veh\u00edculos","item":"https:\/\/coloringonly.com\/es\/cat\/vehiculos\/"},{"@type":"ListItem","position":3,"name":"Cami\u00f3n De La Basura","item":"https:\/\/coloringonly.com\/es\/camion-de-la-basura\/"},{"@type":"ListItem","position":4,"name":"Lindo Cami\u00f3n de Basura"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/es\/#website","url":"https:\/\/coloringonly.com\/es\/","name":"Coloringonly.com","description":"Free Printable Coloring Pages for Kids","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"277\" src=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":512,"height":473,"file":"Lindo-Cami\u00f3n-de-Basura.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":12251,"source_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Lindo-Cami\u00f3n-de-Basura.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media\/34188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/comments?post=34188"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":12251,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/posts\/12251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}