{"id":45170,"date":"2022-08-01T01:59:36","date_gmt":"2022-08-01T01:59:36","guid":{"rendered":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg"},"modified":"2022-08-01T01:59:36","modified_gmt":"2022-08-01T01:59:36","slug":"estrella-normal","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/es\/pages\/estrella-normal\/","title":{"rendered":"Estrella Normal"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-45170","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estrella Normal para colorear, imprimir e dibujar \u2013ColoringOnly.Com<\/title>\n<meta name=\"description\" content=\"Puede descargar una p\u00e1gina para Estrella Normal colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estrella Normal para colorear, imprimir e dibujar \u2013ColoringOnly.Com\" \/>\n<meta property=\"og:description\" content=\"Puede descargar una p\u00e1gina para Estrella Normal colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Coloringonly.com\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1298\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Estrella-Normal.jpg\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Estrella-Normal.jpg\",\"name\":\"Estrella Normal para colorear, imprimir e dibujar \u2013ColoringOnly.Com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\"},\"datePublished\":\"2022-08-01T01:59:36+00:00\",\"description\":\"Puede descargar una p\u00e1gina para Estrella Normal colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Estrella-Normal.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Estrella-Normal.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Estrella-Normal.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ni\u00f1os\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/cat\\\/ninos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Estrella\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/estrella\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Estrella Normal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\",\"name\":\"Coloringonly.com\",\"description\":\"Free Printable Coloring Pages for Kids\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estrella Normal para colorear, imprimir e dibujar \u2013ColoringOnly.Com","description":"Puede descargar una p\u00e1gina para Estrella Normal colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg","og_locale":"en_US","og_type":"article","og_title":"Estrella Normal para colorear, imprimir e dibujar \u2013ColoringOnly.Com","og_description":"Puede descargar una p\u00e1gina para Estrella Normal colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","og_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg","og_site_name":"Coloringonly.com","og_image":[{"width":1280,"height":1298,"url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg","url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg","name":"Estrella Normal para colorear, imprimir e dibujar \u2013ColoringOnly.Com","isPartOf":{"@id":"https:\/\/coloringonly.com\/es\/#website"},"datePublished":"2022-08-01T01:59:36+00:00","description":"Puede descargar una p\u00e1gina para Estrella Normal colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coloringonly.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ni\u00f1os","item":"https:\/\/coloringonly.com\/es\/cat\/ninos\/"},{"@type":"ListItem","position":3,"name":"Estrella","item":"https:\/\/coloringonly.com\/es\/estrella\/"},{"@type":"ListItem","position":4,"name":"Estrella Normal"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/es\/#website","url":"https:\/\/coloringonly.com\/es\/","name":"Coloringonly.com","description":"Free Printable Coloring Pages for Kids","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"300\" src=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":1298,"file":"Estrella-Normal.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":15395,"source_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Estrella-Normal.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media\/45170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/comments?post=45170"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":15395,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/posts\/15395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}