{"id":45229,"date":"2022-08-02T01:10:22","date_gmt":"2022-08-02T01:10:22","guid":{"rendered":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg"},"modified":"2022-08-02T01:22:20","modified_gmt":"2022-08-02T01:22:20","slug":"feliz-navidad-con-elsa-3","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/es\/pages\/feliz-navidad-con-elsa-3\/","title":{"rendered":"Feliz Navidad con Elsa"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-45229","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feliz Navidad con Elsa para colorear, imprimir e dibujar \u2013ColoringOnly.Com<\/title>\n<meta name=\"description\" content=\"Puede descargar una p\u00e1gina para Feliz Navidad con Elsa colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feliz Navidad con Elsa para colorear, imprimir e dibujar \u2013ColoringOnly.Com\" \/>\n<meta property=\"og:description\" content=\"Puede descargar una p\u00e1gina para Feliz Navidad con Elsa colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Coloringonly.com\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-02T01:22:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"892\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/.\\\/feliz-navidad-con-elsa.jpg\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/.\\\/feliz-navidad-con-elsa.jpg\",\"name\":\"Feliz Navidad con Elsa para colorear, imprimir e dibujar \u2013ColoringOnly.Com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\"},\"datePublished\":\"2022-08-02T01:10:22+00:00\",\"dateModified\":\"2022-08-02T01:22:20+00:00\",\"description\":\"Puede descargar una p\u00e1gina para Feliz Navidad con Elsa colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/.\\\/feliz-navidad-con-elsa.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/.\\\/feliz-navidad-con-elsa.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/.\\\/feliz-navidad-con-elsa.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Princesas\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/cat\\\/princesas\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elsa\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/elsa\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Feliz Navidad con Elsa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\",\"name\":\"Coloringonly.com\",\"description\":\"Free Printable Coloring Pages for Kids\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feliz Navidad con Elsa para colorear, imprimir e dibujar \u2013ColoringOnly.Com","description":"Puede descargar una p\u00e1gina para Feliz Navidad con Elsa colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg","og_locale":"en_US","og_type":"article","og_title":"Feliz Navidad con Elsa para colorear, imprimir e dibujar \u2013ColoringOnly.Com","og_description":"Puede descargar una p\u00e1gina para Feliz Navidad con Elsa colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","og_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg","og_site_name":"Coloringonly.com","article_modified_time":"2022-08-02T01:22:20+00:00","og_image":[{"width":700,"height":892,"url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg","url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg","name":"Feliz Navidad con Elsa para colorear, imprimir e dibujar \u2013ColoringOnly.Com","isPartOf":{"@id":"https:\/\/coloringonly.com\/es\/#website"},"datePublished":"2022-08-02T01:10:22+00:00","dateModified":"2022-08-02T01:22:20+00:00","description":"Puede descargar una p\u00e1gina para Feliz Navidad con Elsa colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coloringonly.com\/es\/"},{"@type":"ListItem","position":2,"name":"Princesas","item":"https:\/\/coloringonly.com\/es\/cat\/princesas\/"},{"@type":"ListItem","position":3,"name":"Elsa","item":"https:\/\/coloringonly.com\/es\/elsa\/"},{"@type":"ListItem","position":4,"name":"Feliz Navidad con Elsa"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/es\/#website","url":"https:\/\/coloringonly.com\/es\/","name":"Coloringonly.com","description":"Free Printable Coloring Pages for Kids","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"300\" src=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":892,"file":".\/feliz-navidad-con-elsa.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":10018,"source_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/feliz-navidad-con-elsa.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media\/45229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/comments?post=45229"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":10018,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/posts\/10018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}