{"id":47625,"date":"2024-01-30T13:22:38","date_gmt":"2024-01-30T13:22:38","guid":{"rendered":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png"},"modified":"2024-01-30T13:22:51","modified_gmt":"2024-01-30T13:22:51","slug":"vegan-coloring-printable","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/es\/pages\/vegan-coloring-printable\/","title":{"rendered":"Imprimible de Colorear Vegano"},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-47625","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imprimible de Colorear Vegano para colorear, imprimir e dibujar \u2013ColoringOnly.Com<\/title>\n<meta name=\"description\" content=\"Puede descargar una p\u00e1gina para Imprimible de Colorear Vegano colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imprimible de Colorear Vegano para colorear, imprimir e dibujar \u2013ColoringOnly.Com\" \/>\n<meta property=\"og:description\" content=\"Puede descargar una p\u00e1gina para Imprimible de Colorear Vegano colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png\" \/>\n<meta property=\"og:site_name\" content=\"Coloringonly.com\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T13:22:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/vegan-coloring-printable.png\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/vegan-coloring-printable.png\",\"name\":\"Imprimible de Colorear Vegano para colorear, imprimir e dibujar \u2013ColoringOnly.Com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\"},\"datePublished\":\"2024-01-30T13:22:38+00:00\",\"dateModified\":\"2024-01-30T13:22:51+00:00\",\"description\":\"Puede descargar una p\u00e1gina para Imprimible de Colorear Vegano colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/vegan-coloring-printable.png#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/vegan-coloring-printable.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/vegan-coloring-printable.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otros\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/cat\\\/otros\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vegano\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/category\\\/vegano\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Imprimible de Colorear Vegano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\",\"name\":\"Coloringonly.com\",\"description\":\"Free Printable Coloring Pages for Kids\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imprimible de Colorear Vegano para colorear, imprimir e dibujar \u2013ColoringOnly.Com","description":"Puede descargar una p\u00e1gina para Imprimible de Colorear Vegano colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png","og_locale":"en_US","og_type":"article","og_title":"Imprimible de Colorear Vegano para colorear, imprimir e dibujar \u2013ColoringOnly.Com","og_description":"Puede descargar una p\u00e1gina para Imprimible de Colorear Vegano colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","og_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png","og_site_name":"Coloringonly.com","article_modified_time":"2024-01-30T13:22:51+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png","url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png","name":"Imprimible de Colorear Vegano para colorear, imprimir e dibujar \u2013ColoringOnly.Com","isPartOf":{"@id":"https:\/\/coloringonly.com\/es\/#website"},"datePublished":"2024-01-30T13:22:38+00:00","dateModified":"2024-01-30T13:22:51+00:00","description":"Puede descargar una p\u00e1gina para Imprimible de Colorear Vegano colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coloringonly.com\/es\/"},{"@type":"ListItem","position":2,"name":"Otros","item":"https:\/\/coloringonly.com\/es\/cat\/otros\/"},{"@type":"ListItem","position":3,"name":"Vegano","item":"https:\/\/coloringonly.com\/es\/category\/vegano\/"},{"@type":"ListItem","position":4,"name":"Imprimible de Colorear Vegano"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/es\/#website","url":"https:\/\/coloringonly.com\/es\/","name":"Coloringonly.com","description":"Free Printable Coloring Pages for Kids","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png\" class=\"attachment-medium size-medium\" alt=\"Imprimible de Colorear Vegano\" \/><\/a><\/p>\n<p>Imprimible de Colorear Vegano<\/p>\n"},"caption":{"rendered":"<p>Imprimible de Colorear Vegano<\/p>\n"},"alt_text":"Imprimible de Colorear Vegano","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":800,"file":"vegan-coloring-printable.png","filesize":61174,"sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":47620,"source_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/vegan-coloring-printable.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media\/47625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/comments?post=47625"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":47620,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/posts\/47620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}