{"id":49090,"date":"2025-05-04T12:56:15","date_gmt":"2025-05-04T12:56:15","guid":{"rendered":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg"},"modified":"2025-05-04T12:57:56","modified_gmt":"2025-05-04T12:57:56","slug":"free-march-madness-coloring-page","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/es\/pages\/free-march-madness-coloring-page\/","title":{"rendered":"March Madness Gratis"},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-49090","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>March Madness Gratis para colorear, imprimir e dibujar \u2013ColoringOnly.Com<\/title>\n<meta name=\"description\" content=\"Puede descargar una p\u00e1gina para March Madness Gratis colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"March Madness Gratis para colorear, imprimir e dibujar \u2013ColoringOnly.Com\" \/>\n<meta property=\"og:description\" content=\"Puede descargar una p\u00e1gina para March Madness Gratis colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Coloringonly.com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-04T12:57:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/free-march-madness-coloring-page.jpg\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/free-march-madness-coloring-page.jpg\",\"name\":\"March Madness Gratis para colorear, imprimir e dibujar \u2013ColoringOnly.Com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\"},\"datePublished\":\"2025-05-04T12:56:15+00:00\",\"dateModified\":\"2025-05-04T12:57:56+00:00\",\"description\":\"Puede descargar una p\u00e1gina para March Madness Gratis colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/free-march-madness-coloring-page.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/free-march-madness-coloring-page.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/free-march-madness-coloring-page.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/cat\\\/deportes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Locura de Marzo\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/category\\\/locura-de-marzo\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"March Madness Gratis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\",\"name\":\"Coloringonly.com\",\"description\":\"Free Printable Coloring Pages for Kids\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"March Madness Gratis para colorear, imprimir e dibujar \u2013ColoringOnly.Com","description":"Puede descargar una p\u00e1gina para March Madness Gratis colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg","og_locale":"en_US","og_type":"article","og_title":"March Madness Gratis para colorear, imprimir e dibujar \u2013ColoringOnly.Com","og_description":"Puede descargar una p\u00e1gina para March Madness Gratis colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","og_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg","og_site_name":"Coloringonly.com","article_modified_time":"2025-05-04T12:57:56+00:00","og_image":[{"width":800,"height":1000,"url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg","url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg","name":"March Madness Gratis para colorear, imprimir e dibujar \u2013ColoringOnly.Com","isPartOf":{"@id":"https:\/\/coloringonly.com\/es\/#website"},"datePublished":"2025-05-04T12:56:15+00:00","dateModified":"2025-05-04T12:57:56+00:00","description":"Puede descargar una p\u00e1gina para March Madness Gratis colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coloringonly.com\/es\/"},{"@type":"ListItem","position":2,"name":"Deportes","item":"https:\/\/coloringonly.com\/es\/cat\/deportes\/"},{"@type":"ListItem","position":3,"name":"Locura de Marzo","item":"https:\/\/coloringonly.com\/es\/category\/locura-de-marzo\/"},{"@type":"ListItem","position":4,"name":"March Madness Gratis"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/es\/#website","url":"https:\/\/coloringonly.com\/es\/","name":"Coloringonly.com","description":"Free Printable Coloring Pages for Kids","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg\" class=\"attachment-medium size-medium\" alt=\"March Madness Gratis P\u00e1gina para Colorear\" \/><\/a><\/p>\n<p>March Madness Gratis P\u00e1gina para Colorear<\/p>\n"},"caption":{"rendered":"<p>March Madness Gratis P\u00e1gina para Colorear<\/p>\n"},"alt_text":"March Madness Gratis P\u00e1gina para Colorear","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":1000,"file":"free-march-madness-coloring-page.jpg","filesize":655799,"sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":49082,"source_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/free-march-madness-coloring-page.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media\/49090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/comments?post=49090"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":49082,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/posts\/49082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}