{"id":49750,"date":"2026-05-09T11:27:10","date_gmt":"2026-05-09T11:27:10","guid":{"rendered":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp"},"modified":"2026-05-09T11:38:44","modified_gmt":"2026-05-09T11:38:44","slug":"astronautas-amigos-en-planeta-alienigena-para-pagina-de-colorear","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/es\/pages\/astronautas-amigos-en-planeta-alienigena-para-pagina-de-colorear\/","title":{"rendered":"Astronautas Amigos En Planeta Alien\u00edgena"},"author":16,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-49750","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Astronautas Amigos En Planeta Alien\u00edgena para colorear, imprimir e dibujar \u2013ColoringOnly.Com<\/title>\n<meta name=\"description\" content=\"Puede descargar una p\u00e1gina para Astronautas Amigos En Planeta Alien\u00edgena colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Astronautas Amigos En Planeta Alien\u00edgena para colorear, imprimir e dibujar \u2013ColoringOnly.Com\" \/>\n<meta property=\"og:description\" content=\"Puede descargar una p\u00e1gina para Astronautas Amigos En Planeta Alien\u00edgena colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp\" \/>\n<meta property=\"og:site_name\" content=\"Coloringonly.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T11:38:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"637\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp\",\"name\":\"Astronautas Amigos En Planeta Alien\u00edgena para colorear, imprimir e dibujar \u2013ColoringOnly.Com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\"},\"datePublished\":\"2026-05-09T11:27:10+00:00\",\"dateModified\":\"2026-05-09T11:38:44+00:00\",\"description\":\"Puede descargar una p\u00e1gina para Astronautas Amigos En Planeta Alien\u00edgena colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Astronautas Amigos En Planeta Alien\u00edgena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\",\"name\":\"Coloringonly.com\",\"description\":\"Free Printable Coloring Pages for Kids\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Astronautas Amigos En Planeta Alien\u00edgena para colorear, imprimir e dibujar \u2013ColoringOnly.Com","description":"Puede descargar una p\u00e1gina para Astronautas Amigos En Planeta Alien\u00edgena colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp","og_locale":"en_US","og_type":"article","og_title":"Astronautas Amigos En Planeta Alien\u00edgena para colorear, imprimir e dibujar \u2013ColoringOnly.Com","og_description":"Puede descargar una p\u00e1gina para Astronautas Amigos En Planeta Alien\u00edgena colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","og_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp","og_site_name":"Coloringonly.com","article_modified_time":"2026-05-09T11:38:44+00:00","og_image":[{"width":637,"height":512,"url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp","url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp","name":"Astronautas Amigos En Planeta Alien\u00edgena para colorear, imprimir e dibujar \u2013ColoringOnly.Com","isPartOf":{"@id":"https:\/\/coloringonly.com\/es\/#website"},"datePublished":"2026-05-09T11:27:10+00:00","dateModified":"2026-05-09T11:38:44+00:00","description":"Puede descargar una p\u00e1gina para Astronautas Amigos En Planeta Alien\u00edgena colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coloringonly.com\/es\/"},{"@type":"ListItem","position":2,"name":"Astronautas Amigos En Planeta Alien\u00edgena"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/es\/#website","url":"https:\/\/coloringonly.com\/es\/","name":"Coloringonly.com","description":"Free Printable Coloring Pages for Kids","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"241\" src=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp\" class=\"attachment-medium size-medium\" alt=\"Astronautas Amigos En Planeta Alien\u00edgena Para P\u00e1gina De Colorear\" \/><\/a><\/p>\n<p>Astronautas Amigos En Planeta Alien\u00edgena Para P\u00e1gina De Colorear<\/p>\n"},"caption":{"rendered":"<p>Astronautas Amigos En Planeta Alien\u00edgena Para P\u00e1gina De Colorear<\/p>\n"},"alt_text":"Astronautas Amigos En Planeta Alien\u00edgena Para P\u00e1gina De Colorear","media_type":"image","mime_type":"image\/webp","media_details":{"width":637,"height":512,"file":"Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp","filesize":37730,"sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/Astronautas-Amigos-En-Planeta-Alienigena-Para-Pagina-De-Colorear.webp","_links":{"self":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media\/49750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/comments?post=49750"}]}}