{"id":936,"date":"2020-09-11T12:00:44","date_gmt":"2020-09-11T12:00:44","guid":{"rendered":"https:\/\/dibujos-colorear.com\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png"},"modified":"2021-08-06T03:50:12","modified_gmt":"2021-08-06T03:50:12","slug":"entradas-de-la-copa-del-mundo-2018","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/es\/pages\/entradas-de-la-copa-del-mundo-2018\/","title":{"rendered":"Entradas de la Copa del Mundo 2018"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-936","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entradas de la Copa del Mundo 2018 para colorear, imprimir e dibujar \u2013ColoringOnly.Com<\/title>\n<meta name=\"description\" content=\"Puede descargar una p\u00e1gina para Entradas de la Copa del Mundo 2018 colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entradas de la Copa del Mundo 2018 para colorear, imprimir e dibujar \u2013ColoringOnly.Com\" \/>\n<meta property=\"og:description\" content=\"Puede descargar una p\u00e1gina para Entradas de la Copa del Mundo 2018 colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png\" \/>\n<meta property=\"og:site_name\" content=\"Coloringonly.com\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-06T03:50:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/.\\\/entradas-de-la-copa-del-mundo-2018.png\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/.\\\/entradas-de-la-copa-del-mundo-2018.png\",\"name\":\"Entradas de la Copa del Mundo 2018 para colorear, imprimir e dibujar \u2013ColoringOnly.Com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\"},\"datePublished\":\"2020-09-11T12:00:44+00:00\",\"dateModified\":\"2021-08-06T03:50:12+00:00\",\"description\":\"Puede descargar una p\u00e1gina para Entradas de la Copa del Mundo 2018 colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/.\\\/entradas-de-la-copa-del-mundo-2018.png#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/.\\\/entradas-de-la-copa-del-mundo-2018.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/images\\\/imgcolor\\\/.\\\/entradas-de-la-copa-del-mundo-2018.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deportes\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/cat\\\/deportes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"F\u00fatbol\",\"item\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/futbol\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Entradas de la Copa del Mundo 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/\",\"name\":\"Coloringonly.com\",\"description\":\"Free Printable Coloring Pages for Kids\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coloringonly.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entradas de la Copa del Mundo 2018 para colorear, imprimir e dibujar \u2013ColoringOnly.Com","description":"Puede descargar una p\u00e1gina para Entradas de la Copa del Mundo 2018 colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png","og_locale":"en_US","og_type":"article","og_title":"Entradas de la Copa del Mundo 2018 para colorear, imprimir e dibujar \u2013ColoringOnly.Com","og_description":"Puede descargar una p\u00e1gina para Entradas de la Copa del Mundo 2018 colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","og_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png","og_site_name":"Coloringonly.com","article_modified_time":"2021-08-06T03:50:12+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png","url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png","name":"Entradas de la Copa del Mundo 2018 para colorear, imprimir e dibujar \u2013ColoringOnly.Com","isPartOf":{"@id":"https:\/\/coloringonly.com\/es\/#website"},"datePublished":"2020-09-11T12:00:44+00:00","dateModified":"2021-08-06T03:50:12+00:00","description":"Puede descargar una p\u00e1gina para Entradas de la Copa del Mundo 2018 colorear para imprimir gratis. Tambi\u00e9n puedes colorear online aqu\u00ed.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/coloringonly.com\/es\/"},{"@type":"ListItem","position":2,"name":"Deportes","item":"https:\/\/coloringonly.com\/es\/cat\/deportes\/"},{"@type":"ListItem","position":3,"name":"F\u00fatbol","item":"https:\/\/coloringonly.com\/es\/futbol\/"},{"@type":"ListItem","position":4,"name":"Entradas de la Copa del Mundo 2018"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/es\/#website","url":"https:\/\/coloringonly.com\/es\/","name":"Coloringonly.com","description":"Free Printable Coloring Pages for Kids","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":700,"height":525,"file":".\/entradas-de-la-copa-del-mundo-2018.png","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":8052,"source_url":"https:\/\/coloringonly.com\/es\/images\/imgcolor\/.\/entradas-de-la-copa-del-mundo-2018.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media\/936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/comments?post=936"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":8052,"href":"https:\/\/coloringonly.com\/es\/wp-json\/wp\/v2\/posts\/8052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}