{"id":230972,"date":"2020-09-11T16:00:45","date_gmt":"2020-09-11T16:00:45","guid":{"rendered":"https:\/\/helppdf.com\/images\/imgcolor\/.\/1560931028-ezreal-a4.gif"},"modified":"2024-08-25T14:27:31","modified_gmt":"2024-08-25T14:27:31","slug":"ezreal-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/jogos\/liga-das-lendas\/attachment\/ezreal-2\/","title":{"rendered":"Ezreal"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-230972","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ezreal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/jogos\/liga-das-lendas\/attachment\/ezreal-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T14:27:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ezreal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/jogos\/liga-das-lendas\/attachment\/ezreal-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T14:27:31+00:00","og_image":[{"width":900,"height":707,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/jogos\/liga-das-lendas\/attachment\/ezreal-2\/","url":"https:\/\/coloringonly.com\/pt\/jogos\/liga-das-lendas\/attachment\/ezreal-2\/","name":"Ezreal Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2020-09-11T16:00:45+00:00","dateModified":"2024-08-25T14:27:31+00:00","description":"Free printable Ezreal coloring page. You can download Ezreal coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/jogos\/liga-das-lendas\/attachment\/ezreal-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/jogos\/liga-das-lendas\/attachment\/ezreal-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/jogos\/liga-das-lendas\/attachment\/ezreal-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Jogos","item":"https:\/\/coloringonly.com\/pt\/category\/jogos\/"},{"@type":"ListItem","position":3,"name":"Liga das Lendas","item":"https:\/\/coloringonly.com\/pt\/jogos\/liga-das-lendas\/"},{"@type":"ListItem","position":4,"name":"Ezreal"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4.gif'><img decoding=\"async\" width=\"300\" height=\"236\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4-300x236.gif\" class=\"attachment-medium size-medium\" alt=\"Liga das Lendas\" srcset=\"https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4-300x236.gif 300w, https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4-768x603.gif 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/gif","media_details":{"width":900,"height":707,"file":"1560931028-ezreal-a4.gif","filesize":114931,"sizes":{"medium":{"file":"1560931028-ezreal-a4-300x236.gif","width":300,"height":236,"filesize":25657,"mime_type":"image\/gif","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4-300x236.gif"},"thumbnail":{"file":"1560931028-ezreal-a4-150x150.gif","width":150,"height":150,"filesize":11274,"mime_type":"image\/gif","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4-150x150.gif"},"medium_large":{"file":"1560931028-ezreal-a4-768x603.gif","width":768,"height":603,"filesize":226582,"mime_type":"image\/gif","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4-768x603.gif"},"full":{"file":"1560931028-ezreal-a4.gif","width":900,"height":707,"mime_type":"image\/gif","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4.gif"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":230950,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/1560931028-ezreal-a4.gif","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/230972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=230972"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":230950,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/230950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}