{"id":234144,"date":"2020-09-11T14:04:41","date_gmt":"2020-09-11T14:04:41","guid":{"rendered":"https:\/\/helppdf.com\/images\/imgcolor\/.\/1539749335-frozen-coloring-pages-olaf-coloring-pages-elsa-coloring-pages-for-kids-91.gif"},"modified":"2024-08-25T10:11:09","modified_gmt":"2024-08-25T10:11:09","slug":"happy-olaf-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/jogos\/olaf\/attachment\/happy-olaf-2\/","title":{"rendered":"Olaf feliz"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-234144","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Olaf feliz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/jogos\/olaf\/attachment\/happy-olaf-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T10:11:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/1539749335-frozen-coloring-pages-olaf-coloring-pages-elsa-coloring-pages-for-kids-91.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"839\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olaf feliz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/jogos\/olaf\/attachment\/happy-olaf-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T10:11:09+00:00","og_image":[{"width":700,"height":839,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/1539749335-frozen-coloring-pages-olaf-coloring-pages-elsa-coloring-pages-for-kids-91.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/jogos\/olaf\/attachment\/happy-olaf-2\/","url":"https:\/\/coloringonly.com\/pt\/jogos\/olaf\/attachment\/happy-olaf-2\/","name":"Olaf feliz Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2020-09-11T14:04:41+00:00","dateModified":"2024-08-25T10:11:09+00:00","description":"Free printable Olaf feliz coloring page. You can download Olaf feliz coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/jogos\/olaf\/attachment\/happy-olaf-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/jogos\/olaf\/attachment\/happy-olaf-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/jogos\/olaf\/attachment\/happy-olaf-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Jogos","item":"https:\/\/coloringonly.com\/pt\/category\/jogos\/"},{"@type":"ListItem","position":3,"name":"Olaf","item":"https:\/\/coloringonly.com\/pt\/jogos\/olaf\/"},{"@type":"ListItem","position":4,"name":"Olaf feliz"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/1539749335-frozen-coloring-pages-olaf-coloring-pages-elsa-coloring-pages-for-kids-91.gif'><img decoding=\"async\" width=\"700\" height=\"839\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/1539749335-frozen-coloring-pages-olaf-coloring-pages-elsa-coloring-pages-for-kids-91.gif\" class=\"attachment-medium size-medium\" alt=\"Olaf\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/gif","media_details":{"width":700,"height":839,"file":"\/1539749335-frozen-coloring-pages-olaf-coloring-pages-elsa-coloring-pages-for-kids-91.gif","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":13200},"post":234142,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/1539749335-frozen-coloring-pages-olaf-coloring-pages-elsa-coloring-pages-for-kids-91.gif","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/234144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=234144"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":234142,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/234142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}