{"id":240092,"date":"2023-11-02T04:36:08","date_gmt":"2023-11-02T04:36:08","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages.png"},"modified":"2024-08-25T10:46:51","modified_gmt":"2024-08-25T10:46:51","slug":"scarecrow-is-standing-in-the-field-with-animals-coloring-pages-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/espantalho\/attachment\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-2\/","title":{"rendered":"O espantalho est\u00e1 de p\u00e9 no campo com os animais"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-240092","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O espantalho est\u00e1 de p\u00e9 no campo com os animais<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/espantalho\/attachment\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T10:46:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O espantalho est\u00e1 de p\u00e9 no campo com os animais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/espantalho\/attachment\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T10:46:51+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/espantalho\/attachment\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-2\/","url":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/espantalho\/attachment\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-2\/","name":"O espantalho est\u00e1 de p\u00e9 no campo com os animais Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2023-11-02T04:36:08+00:00","dateModified":"2024-08-25T10:46:51+00:00","description":"Free printable O espantalho est\u00e1 de p\u00e9 no campo com os animais coloring page. You can download O espantalho est\u00e1 de p\u00e9 no campo com os animais coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/espantalho\/attachment\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/uncategorized-pt\/espantalho\/attachment\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/espantalho\/attachment\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Uncategorized @pt","item":"https:\/\/coloringonly.com\/pt\/category\/uncategorized-pt\/"},{"@type":"ListItem","position":3,"name":"Espantalho","item":"https:\/\/coloringonly.com\/pt\/miscellaneous\/scarecrow\/"},{"@type":"ListItem","position":4,"name":"O espantalho est\u00e1 de p\u00e9 no campo com os animais"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages.png'><img decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-225x300.png\" class=\"attachment-medium size-medium\" alt=\"Espantalho est\u00e1 parado no campo com desenhos de animais para colorir\" srcset=\"https:\/\/coloringonly.com\/images\/imgcolor\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-225x300.png 225w, https:\/\/coloringonly.com\/images\/imgcolor\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-150x200.png 150w, https:\/\/coloringonly.com\/images\/imgcolor\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages.png 600w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Espantalho est\u00e1 parado no campo com desenhos de animais para colorir<\/p>\n"},"caption":{"rendered":"<p>Espantalho est\u00e1 parado no campo com desenhos de animais para colorir<\/p>\n"},"alt_text":"Espantalho est\u00e1 parado no campo com desenhos de animais para colorir","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":800,"file":".\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages.png","filesize":75467,"sizes":{"thumbnail":{"file":"scarecrow-is-standing-in-the-field-with-animals-coloring-pages-150x150.png","width":150,"height":150,"filesize":11015,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-150x150.png"},"medium":{"file":"scarecrow-is-standing-in-the-field-with-animals-coloring-pages-225x300.png","width":225,"height":300,"filesize":22742,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-225x300.png"},"web-stories-publisher-logo":{"file":"scarecrow-is-standing-in-the-field-with-animals-coloring-pages-96x96.png","width":96,"height":96,"filesize":5462,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-96x96.png"},"web-stories-thumbnail":{"file":"scarecrow-is-standing-in-the-field-with-animals-coloring-pages-150x200.png","width":150,"height":200,"filesize":12453,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages-150x200.png"},"full":{"file":"scarecrow-is-standing-in-the-field-with-animals-coloring-pages.png","width":600,"height":800,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":239978,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/scarecrow-is-standing-in-the-field-with-animals-coloring-pages.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/240092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=240092"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":239978,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/239978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}