{"id":241712,"date":"2020-09-11T13:03:00","date_gmt":"2020-09-11T13:03:00","guid":{"rendered":"https:\/\/helppdf.com\/images\/imgcolor\/.\/1532317680-happy-donald-duck-a4.png"},"modified":"2024-08-25T10:52:22","modified_gmt":"2024-08-25T10:52:22","slug":"happy-donald-duck-3","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/caricatura\/pato-donald\/attachment\/happy-donald-duck-3\/","title":{"rendered":"Pato Donald feliz"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-241712","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pato Donald feliz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/caricatura\/pato-donald\/attachment\/happy-donald-duck-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T10:52:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/1532317680-happy-donald-duck-a4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"870\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pato Donald feliz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/caricatura\/pato-donald\/attachment\/happy-donald-duck-3\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T10:52:22+00:00","og_image":[{"width":800,"height":870,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/1532317680-happy-donald-duck-a4.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/caricatura\/pato-donald\/attachment\/happy-donald-duck-3\/","url":"https:\/\/coloringonly.com\/pt\/caricatura\/pato-donald\/attachment\/happy-donald-duck-3\/","name":"Pato Donald feliz Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2020-09-11T13:03:00+00:00","dateModified":"2024-08-25T10:52:22+00:00","description":"Free printable Pato Donald feliz coloring page. You can download Pato Donald feliz coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/caricatura\/pato-donald\/attachment\/happy-donald-duck-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/caricatura\/pato-donald\/attachment\/happy-donald-duck-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/caricatura\/pato-donald\/attachment\/happy-donald-duck-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Caricatura","item":"https:\/\/coloringonly.com\/pt\/category\/caricatura\/"},{"@type":"ListItem","position":3,"name":"Pato Donald","item":"https:\/\/coloringonly.com\/pt\/caricatura\/pato-donald\/"},{"@type":"ListItem","position":4,"name":"Pato Donald feliz"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/.\/1532317680-happy-donald-duck-a4.png'><img decoding=\"async\" width=\"276\" height=\"300\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/1532317680-happy-donald-duck-a4-276x300.png\" class=\"attachment-medium size-medium\" alt=\"Pato Donald\" srcset=\"https:\/\/coloringonly.com\/images\/imgcolor\/1532317680-happy-donald-duck-a4-276x300.png 276w, https:\/\/coloringonly.com\/images\/imgcolor\/1532317680-happy-donald-duck-a4-768x835.png 768w, https:\/\/coloringonly.com\/images\/imgcolor\/1532317680-happy-donald-duck-a4.png 800w\" sizes=\"(max-width: 276px) 100vw, 276px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":800,"height":870,"file":".\/1532317680-happy-donald-duck-a4.png","filesize":119430,"sizes":{"medium":{"file":"1532317680-happy-donald-duck-a4-276x300.png","width":276,"height":300,"filesize":17135,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/1532317680-happy-donald-duck-a4-276x300.png"},"thumbnail":{"file":"1532317680-happy-donald-duck-a4-150x150.png","width":150,"height":150,"filesize":6960,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/1532317680-happy-donald-duck-a4-150x150.png"},"medium_large":{"file":"1532317680-happy-donald-duck-a4-768x835.png","width":768,"height":835,"filesize":72909,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/1532317680-happy-donald-duck-a4-768x835.png"},"full":{"file":"1532317680-happy-donald-duck-a4.png","width":800,"height":870,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/1532317680-happy-donald-duck-a4.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":241707,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/1532317680-happy-donald-duck-a4.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/241712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=241712"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":241707,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/241707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}