{"id":255406,"date":"2023-11-30T20:36:51","date_gmt":"2023-11-30T20:36:51","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages.png"},"modified":"2024-08-25T11:46:39","modified_gmt":"2024-08-25T11:46:39","slug":"gingerbread-man-and-candy-cane-coloring-pages-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/ferias\/homem-pao-de-gengibre\/attachment\/gingerbread-man-and-candy-cane-coloring-pages-2\/","title":{"rendered":"Homem de gengibre e bengala de doces"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-255406","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Homem de gengibre e bengala de doces<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/ferias\/homem-pao-de-gengibre\/attachment\/gingerbread-man-and-candy-cane-coloring-pages-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T11:46:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Homem de gengibre e bengala de doces","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/ferias\/homem-pao-de-gengibre\/attachment\/gingerbread-man-and-candy-cane-coloring-pages-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T11:46:39+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/ferias\/homem-pao-de-gengibre\/attachment\/gingerbread-man-and-candy-cane-coloring-pages-2\/","url":"https:\/\/coloringonly.com\/pt\/ferias\/homem-pao-de-gengibre\/attachment\/gingerbread-man-and-candy-cane-coloring-pages-2\/","name":"Homem de gengibre e bengala de doces Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2023-11-30T20:36:51+00:00","dateModified":"2024-08-25T11:46:39+00:00","description":"Free printable Homem de gengibre e bengala de doces coloring page. You can download Homem de gengibre e bengala de doces coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/ferias\/homem-pao-de-gengibre\/attachment\/gingerbread-man-and-candy-cane-coloring-pages-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/ferias\/homem-pao-de-gengibre\/attachment\/gingerbread-man-and-candy-cane-coloring-pages-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/ferias\/homem-pao-de-gengibre\/attachment\/gingerbread-man-and-candy-cane-coloring-pages-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"F\u00e9rias","item":"https:\/\/coloringonly.com\/pt\/category\/ferias\/"},{"@type":"ListItem","position":3,"name":"Homem de gengibre","item":"https:\/\/coloringonly.com\/pt\/holidays\/gingerbread-man\/"},{"@type":"ListItem","position":4,"name":"Homem de gengibre e bengala de doces"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages.png'><img decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages-225x300.png\" class=\"attachment-medium size-medium\" alt=\"Desenhos de Boneco de Gengibre e Bengala de Doces para colorir\" srcset=\"https:\/\/coloringonly.com\/images\/imgcolor\/gingerbread-man-and-candy-cane-coloring-pages-225x300.png 225w, https:\/\/coloringonly.com\/images\/imgcolor\/gingerbread-man-and-candy-cane-coloring-pages-113x150.png 113w, https:\/\/coloringonly.com\/images\/imgcolor\/gingerbread-man-and-candy-cane-coloring-pages-150x200.png 150w, https:\/\/coloringonly.com\/images\/imgcolor\/gingerbread-man-and-candy-cane-coloring-pages.png 600w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p>Desenhos de Boneco de Gengibre e Bengala de Doces para colorir<\/p>\n"},"caption":{"rendered":"<p>Desenhos de Boneco de Gengibre e Bengala de Doces para colorir<\/p>\n"},"alt_text":"Desenhos de Boneco de Gengibre e Bengala de Doces para colorir","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":800,"file":".\/gingerbread-man-and-candy-cane-coloring-pages.png","filesize":75067,"sizes":{"medium":{"file":"gingerbread-man-and-candy-cane-coloring-pages-225x300.png","width":225,"height":300,"filesize":18619,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages-225x300.png"},"thumbnail":{"file":"gingerbread-man-and-candy-cane-coloring-pages-113x150.png","width":113,"height":150,"filesize":6621,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages-113x150.png"},"web-stories-publisher-logo":{"file":"gingerbread-man-and-candy-cane-coloring-pages-96x96.png","width":96,"height":96,"filesize":4415,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages-96x96.png"},"web-stories-thumbnail":{"file":"gingerbread-man-and-candy-cane-coloring-pages-150x200.png","width":150,"height":200,"filesize":10482,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages-150x200.png"},"full":{"file":"gingerbread-man-and-candy-cane-coloring-pages.png","width":600,"height":800,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":255401,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/gingerbread-man-and-candy-cane-coloring-pages.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/255406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=255406"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":255401,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/255401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}