{"id":256959,"date":"2021-05-07T07:23:17","date_gmt":"2021-05-07T07:23:17","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page.jpg"},"modified":"2024-08-25T11:53:26","modified_gmt":"2024-08-25T11:53:26","slug":"jonah-and-the-whale-4-coloring-page-3","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/jonas-e-a-baleia\/attachment\/jonah-and-the-whale-4-coloring-page-3\/","title":{"rendered":"Jonas e a Baleia 4"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-256959","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jonas e a Baleia 4<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/jonas-e-a-baleia\/attachment\/jonah-and-the-whale-4-coloring-page-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T11:53:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"802\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jonas e a Baleia 4","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/jonas-e-a-baleia\/attachment\/jonah-and-the-whale-4-coloring-page-3\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T11:53:26+00:00","og_image":[{"width":802,"height":800,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/jonas-e-a-baleia\/attachment\/jonah-and-the-whale-4-coloring-page-3\/","url":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/jonas-e-a-baleia\/attachment\/jonah-and-the-whale-4-coloring-page-3\/","name":"Jonas e a Baleia 4 Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2021-05-07T07:23:17+00:00","dateModified":"2024-08-25T11:53:26+00:00","description":"Free printable Jonas e a Baleia 4 coloring page. You can download Jonas e a Baleia 4 coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/jonas-e-a-baleia\/attachment\/jonah-and-the-whale-4-coloring-page-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/uncategorized-pt\/jonas-e-a-baleia\/attachment\/jonah-and-the-whale-4-coloring-page-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/uncategorized-pt\/jonas-e-a-baleia\/attachment\/jonah-and-the-whale-4-coloring-page-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Uncategorized @pt","item":"https:\/\/coloringonly.com\/pt\/category\/uncategorized-pt\/"},{"@type":"ListItem","position":3,"name":"Jonas e a Baleia","item":"https:\/\/coloringonly.com\/pt\/miscellaneous\/jonah-and-the-whale\/"},{"@type":"ListItem","position":4,"name":"Jonas e a Baleia 4"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page.jpg'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Jonas e a Baleia\" srcset=\"https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page-300x300.jpg 300w, https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page-150x150.jpg 150w, https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page-768x766.jpg 768w, https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page.jpg 802w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":802,"height":800,"file":"Jonah-and-the-Whale-4-coloring-page.jpg","filesize":121147,"sizes":{"medium":{"file":"Jonah-and-the-Whale-4-coloring-page-300x300.jpg","width":300,"height":300,"filesize":25427,"mime_type":"image\/jpeg","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page-300x300.jpg"},"thumbnail":{"file":"Jonah-and-the-Whale-4-coloring-page-150x150.jpg","width":150,"height":150,"filesize":7475,"mime_type":"image\/jpeg","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page-150x150.jpg"},"medium_large":{"file":"Jonah-and-the-Whale-4-coloring-page-768x766.jpg","width":768,"height":766,"filesize":114752,"mime_type":"image\/jpeg","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page-768x766.jpg"},"full":{"file":"Jonah-and-the-Whale-4-coloring-page.jpg","width":802,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":256950,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Jonah-and-the-Whale-4-coloring-page.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/256959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=256959"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":256950,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/256950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}