{"id":262078,"date":"2021-04-03T01:05:43","date_gmt":"2021-04-03T01:05:43","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Easter-Eggs-Mandala-1-coloring-page.jpg"},"modified":"2024-08-25T12:10:23","modified_gmt":"2024-08-25T12:10:23","slug":"easter-eggs-mandala-1-coloring-page-3","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/ferias\/mandala-de-pascoa\/attachment\/easter-eggs-mandala-1-coloring-page-3\/","title":{"rendered":"Mandala de ovos de P\u00e1scoa 1"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-262078","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mandala de ovos de P\u00e1scoa 1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/ferias\/mandala-de-pascoa\/attachment\/easter-eggs-mandala-1-coloring-page-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T12:10:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/Easter-Eggs-Mandala-1-coloring-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"652\" \/>\n\t<meta property=\"og:image:height\" content=\"652\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mandala de ovos de P\u00e1scoa 1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/ferias\/mandala-de-pascoa\/attachment\/easter-eggs-mandala-1-coloring-page-3\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T12:10:23+00:00","og_image":[{"width":652,"height":652,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/Easter-Eggs-Mandala-1-coloring-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/ferias\/mandala-de-pascoa\/attachment\/easter-eggs-mandala-1-coloring-page-3\/","url":"https:\/\/coloringonly.com\/pt\/ferias\/mandala-de-pascoa\/attachment\/easter-eggs-mandala-1-coloring-page-3\/","name":"Mandala de ovos de P\u00e1scoa 1 Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2021-04-03T01:05:43+00:00","dateModified":"2024-08-25T12:10:23+00:00","description":"Free printable Mandala de ovos de P\u00e1scoa 1 coloring page. You can download Mandala de ovos de P\u00e1scoa 1 coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/ferias\/mandala-de-pascoa\/attachment\/easter-eggs-mandala-1-coloring-page-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/ferias\/mandala-de-pascoa\/attachment\/easter-eggs-mandala-1-coloring-page-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/ferias\/mandala-de-pascoa\/attachment\/easter-eggs-mandala-1-coloring-page-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"F\u00e9rias","item":"https:\/\/coloringonly.com\/pt\/category\/ferias\/"},{"@type":"ListItem","position":3,"name":"Mandala de P\u00e1scoa","item":"https:\/\/coloringonly.com\/pt\/holidays\/easter-mandala\/"},{"@type":"ListItem","position":4,"name":"Mandala de ovos de P\u00e1scoa 1"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/Easter-Eggs-Mandala-1-coloring-page.jpg'><img decoding=\"async\" width=\"652\" height=\"652\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/Easter-Eggs-Mandala-1-coloring-page.jpg\" class=\"attachment-medium size-medium\" alt=\"Mandala de P\u00e1scoa\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":652,"height":652,"file":"Easter-Eggs-Mandala-1-coloring-page.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":262066,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Easter-Eggs-Mandala-1-coloring-page.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/262078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=262078"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":262066,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/262066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}