{"id":268364,"date":"2021-09-18T00:40:31","date_gmt":"2021-09-18T00:40:31","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page.jpg"},"modified":"2024-08-25T12:29:43","modified_gmt":"2024-08-25T12:29:43","slug":"cartoon-scallop-coloring-page-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/animais\/vieira\/attachment\/cartoon-scallop-coloring-page-2\/","title":{"rendered":"Vieira dos desenhos animados"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-268364","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vieira dos desenhos animados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/animais\/vieira\/attachment\/cartoon-scallop-coloring-page-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T12:29:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"988\" \/>\n\t<meta property=\"og:image:height\" content=\"798\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vieira dos desenhos animados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/animais\/vieira\/attachment\/cartoon-scallop-coloring-page-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T12:29:43+00:00","og_image":[{"width":988,"height":798,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/animais\/vieira\/attachment\/cartoon-scallop-coloring-page-2\/","url":"https:\/\/coloringonly.com\/pt\/animais\/vieira\/attachment\/cartoon-scallop-coloring-page-2\/","name":"Vieira dos desenhos animados Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2021-09-18T00:40:31+00:00","dateModified":"2024-08-25T12:29:43+00:00","description":"Free printable Vieira dos desenhos animados coloring page. You can download Vieira dos desenhos animados coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/animais\/vieira\/attachment\/cartoon-scallop-coloring-page-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/animais\/vieira\/attachment\/cartoon-scallop-coloring-page-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/animais\/vieira\/attachment\/cartoon-scallop-coloring-page-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Animais","item":"https:\/\/coloringonly.com\/pt\/category\/animais\/"},{"@type":"ListItem","position":3,"name":"Vieira","item":"https:\/\/coloringonly.com\/pt\/animals\/scallop\/"},{"@type":"ListItem","position":4,"name":"Vieira dos desenhos animados"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page.jpg'><img decoding=\"async\" width=\"300\" height=\"242\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page-300x242.jpg\" class=\"attachment-medium size-medium\" alt=\"Vieira\" srcset=\"https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page-300x242.jpg 300w, https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page-768x620.jpg 768w, https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page.jpg 988w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":988,"height":798,"file":"Cartoon-Scallop-coloring-page.jpg","filesize":33284,"sizes":{"medium":{"file":"Cartoon-Scallop-coloring-page-300x242.jpg","width":300,"height":242,"filesize":10855,"mime_type":"image\/jpeg","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page-300x242.jpg"},"thumbnail":{"file":"Cartoon-Scallop-coloring-page-150x150.jpg","width":150,"height":150,"filesize":4916,"mime_type":"image\/jpeg","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page-150x150.jpg"},"medium_large":{"file":"Cartoon-Scallop-coloring-page-768x620.jpg","width":768,"height":620,"filesize":34219,"mime_type":"image\/jpeg","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page-768x620.jpg"},"full":{"file":"Cartoon-Scallop-coloring-page.jpg","width":988,"height":798,"mime_type":"image\/jpeg","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":268340,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Cartoon-Scallop-coloring-page.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/268364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=268364"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":268340,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/268340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}