{"id":281207,"date":"2022-03-21T06:58:07","date_gmt":"2022-03-21T06:58:07","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Rocking-Horse-with-a-Ball-coloring-page.jpg"},"modified":"2024-08-25T13:11:30","modified_gmt":"2024-08-25T13:11:30","slug":"rocking-horse-with-a-ball-coloring-page-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/brinquedos-bonecas\/cavalo-de-balanco\/attachment\/rocking-horse-with-a-ball-coloring-page-2\/","title":{"rendered":"Cavalo de balan\u00e7o com uma bola"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-281207","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cavalo de balan\u00e7o com uma bola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/brinquedos-bonecas\/cavalo-de-balanco\/attachment\/rocking-horse-with-a-ball-coloring-page-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T13:11:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/Rocking-Horse-with-a-Ball-coloring-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"957\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cavalo de balan\u00e7o com uma bola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/brinquedos-bonecas\/cavalo-de-balanco\/attachment\/rocking-horse-with-a-ball-coloring-page-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T13:11:30+00:00","og_image":[{"width":957,"height":718,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/Rocking-Horse-with-a-Ball-coloring-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/brinquedos-bonecas\/cavalo-de-balanco\/attachment\/rocking-horse-with-a-ball-coloring-page-2\/","url":"https:\/\/coloringonly.com\/pt\/brinquedos-bonecas\/cavalo-de-balanco\/attachment\/rocking-horse-with-a-ball-coloring-page-2\/","name":"Cavalo de balan\u00e7o com uma bola Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2022-03-21T06:58:07+00:00","dateModified":"2024-08-25T13:11:30+00:00","description":"Free printable Cavalo de balan\u00e7o com uma bola coloring page. You can download Cavalo de balan\u00e7o com uma bola coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/brinquedos-bonecas\/cavalo-de-balanco\/attachment\/rocking-horse-with-a-ball-coloring-page-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/brinquedos-bonecas\/cavalo-de-balanco\/attachment\/rocking-horse-with-a-ball-coloring-page-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/brinquedos-bonecas\/cavalo-de-balanco\/attachment\/rocking-horse-with-a-ball-coloring-page-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Brinquedos &amp; Bonecas","item":"https:\/\/coloringonly.com\/pt\/category\/brinquedos-bonecas\/"},{"@type":"ListItem","position":3,"name":"Cavalo de balan\u00e7o","item":"https:\/\/coloringonly.com\/pt\/brinquedos-bonecas\/cavalo-de-balanco\/"},{"@type":"ListItem","position":4,"name":"Cavalo de balan\u00e7o com uma bola"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/Rocking-Horse-with-a-Ball-coloring-page.jpg'><img decoding=\"async\" width=\"957\" height=\"718\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/Rocking-Horse-with-a-Ball-coloring-page.jpg\" class=\"attachment-medium size-medium\" alt=\"Cavalo de balan\u00e7o\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":957,"height":718,"file":"Rocking-Horse-with-a-Ball-coloring-page.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":60262},"post":281179,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Rocking-Horse-with-a-Ball-coloring-page.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/281207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=281207"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":281179,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/281179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}