{"id":284472,"date":"2022-04-15T07:17:33","date_gmt":"2022-04-15T07:17:33","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Mommy-Long-Legs-to-Color-coloring-page.jpg"},"modified":"2024-08-25T13:22:57","modified_gmt":"2024-08-25T13:22:57","slug":"mommy-long-legs-to-color-coloring-page-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/jogos\/mamae-pernas-longas\/attachment\/mommy-long-legs-to-color-coloring-page-2\/","title":{"rendered":"Mam\u00e3e pernas longas para colorir"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-284472","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mam\u00e3e pernas longas para colorir<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/jogos\/mamae-pernas-longas\/attachment\/mommy-long-legs-to-color-coloring-page-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T13:22:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/Mommy-Long-Legs-to-Color-coloring-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1125\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mam\u00e3e pernas longas para colorir","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/jogos\/mamae-pernas-longas\/attachment\/mommy-long-legs-to-color-coloring-page-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T13:22:57+00:00","og_image":[{"width":1125,"height":750,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/Mommy-Long-Legs-to-Color-coloring-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/jogos\/mamae-pernas-longas\/attachment\/mommy-long-legs-to-color-coloring-page-2\/","url":"https:\/\/coloringonly.com\/pt\/jogos\/mamae-pernas-longas\/attachment\/mommy-long-legs-to-color-coloring-page-2\/","name":"Mam\u00e3e pernas longas para colorir Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2022-04-15T07:17:33+00:00","dateModified":"2024-08-25T13:22:57+00:00","description":"Free printable Mam\u00e3e pernas longas para colorir coloring page. You can download Mam\u00e3e pernas longas para colorir coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/jogos\/mamae-pernas-longas\/attachment\/mommy-long-legs-to-color-coloring-page-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/jogos\/mamae-pernas-longas\/attachment\/mommy-long-legs-to-color-coloring-page-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/jogos\/mamae-pernas-longas\/attachment\/mommy-long-legs-to-color-coloring-page-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Jogos","item":"https:\/\/coloringonly.com\/pt\/category\/jogos\/"},{"@type":"ListItem","position":3,"name":"Mam\u00e3e Pernas Longas","item":"https:\/\/coloringonly.com\/pt\/jogos\/mamae-pernas-longas\/"},{"@type":"ListItem","position":4,"name":"Mam\u00e3e pernas longas para colorir"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/Mommy-Long-Legs-to-Color-coloring-page.jpg'><img decoding=\"async\" width=\"1125\" height=\"750\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/Mommy-Long-Legs-to-Color-coloring-page.jpg\" class=\"attachment-medium size-medium\" alt=\"Mam\u00e3e Pernas Longas\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1125,"height":750,"file":"Mommy-Long-Legs-to-Color-coloring-page.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":41794},"post":284464,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Mommy-Long-Legs-to-Color-coloring-page.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/284472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=284472"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":284464,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/284464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}