{"id":298940,"date":"2023-05-22T08:09:01","date_gmt":"2023-05-22T08:09:01","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/flag-of-tonga-coloring-page.jpg"},"modified":"2025-10-31T10:54:31","modified_gmt":"2025-10-31T10:54:31","slug":"flag-of-tonga-coloring-page-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/lugares\/bandeira-2\/attachment\/flag-of-tonga-coloring-page-2\/","title":{"rendered":"Bandeira de Tonga"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-298940","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bandeira de Tonga<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/lugares\/bandeira-2\/attachment\/flag-of-tonga-coloring-page-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T10:54:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/flag-of-tonga-coloring-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1061\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bandeira de Tonga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/lugares\/bandeira-2\/attachment\/flag-of-tonga-coloring-page-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2025-10-31T10:54:31+00:00","og_image":[{"width":1500,"height":1061,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/flag-of-tonga-coloring-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/lugares\/bandeira-2\/attachment\/flag-of-tonga-coloring-page-2\/","url":"https:\/\/coloringonly.com\/pt\/lugares\/bandeira-2\/attachment\/flag-of-tonga-coloring-page-2\/","name":"Bandeira de Tonga Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2023-05-22T08:09:01+00:00","dateModified":"2025-10-31T10:54:31+00:00","description":"Free printable Bandeira de Tonga coloring page. You can download Bandeira de Tonga coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/lugares\/bandeira-2\/attachment\/flag-of-tonga-coloring-page-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/lugares\/bandeira-2\/attachment\/flag-of-tonga-coloring-page-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/lugares\/bandeira-2\/attachment\/flag-of-tonga-coloring-page-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Lugares","item":"https:\/\/coloringonly.com\/pt\/category\/lugares\/"},{"@type":"ListItem","position":3,"name":"Bandeira","item":"https:\/\/coloringonly.com\/pt\/lugares\/bandeira-2\/"},{"@type":"ListItem","position":4,"name":"Bandeira de Tonga"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/.\/flag-of-tonga-coloring-page.jpg'><img decoding=\"async\" width=\"1500\" height=\"1061\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/flag-of-tonga-coloring-page.jpg\" class=\"attachment-medium size-medium\" alt=\"Desenho de Bandeira de Tonga para colorir\" \/><\/a><\/p>\n<p>Desenho de Bandeira de Tonga para colorir<\/p>\n"},"caption":{"rendered":"<p>Desenho de Bandeira de Tonga para colorir<\/p>\n"},"alt_text":"Desenho de Bandeira de Tonga para colorir","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1500,"height":1061,"file":".\/flag-of-tonga-coloring-page.jpg","filesize":21912,"sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":298848,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/flag-of-tonga-coloring-page.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/298940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=298940"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":298848,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/298848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}