{"id":300203,"date":"2022-12-21T07:17:12","date_gmt":"2022-12-21T07:17:12","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/canada-flag-and-map-coloring-page-2.png"},"modified":"2025-10-31T10:54:09","modified_gmt":"2025-10-31T10:54:09","slug":"canada-flag-and-map-coloring-page-2-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/lugares\/pagina-de-coloracao-de-mapa-de-pais-com-bandeira\/attachment\/canada-flag-and-map-coloring-page-2-2\/","title":{"rendered":"Bandeira e mapa do Canad\u00e1"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-300203","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bandeira e mapa do Canad\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/lugares\/pagina-de-coloracao-de-mapa-de-pais-com-bandeira\/attachment\/canada-flag-and-map-coloring-page-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T10:54:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/canada-flag-and-map-coloring-page-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bandeira e mapa do Canad\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/lugares\/pagina-de-coloracao-de-mapa-de-pais-com-bandeira\/attachment\/canada-flag-and-map-coloring-page-2-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2025-10-31T10:54:09+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/canada-flag-and-map-coloring-page-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/lugares\/pagina-de-coloracao-de-mapa-de-pais-com-bandeira\/attachment\/canada-flag-and-map-coloring-page-2-2\/","url":"https:\/\/coloringonly.com\/pt\/lugares\/pagina-de-coloracao-de-mapa-de-pais-com-bandeira\/attachment\/canada-flag-and-map-coloring-page-2-2\/","name":"Bandeira e mapa do Canad\u00e1 Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2022-12-21T07:17:12+00:00","dateModified":"2025-10-31T10:54:09+00:00","description":"Free printable Bandeira e mapa do Canad\u00e1 coloring page. You can download Bandeira e mapa do Canad\u00e1 coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/lugares\/pagina-de-coloracao-de-mapa-de-pais-com-bandeira\/attachment\/canada-flag-and-map-coloring-page-2-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/lugares\/pagina-de-coloracao-de-mapa-de-pais-com-bandeira\/attachment\/canada-flag-and-map-coloring-page-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/lugares\/pagina-de-coloracao-de-mapa-de-pais-com-bandeira\/attachment\/canada-flag-and-map-coloring-page-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Lugares","item":"https:\/\/coloringonly.com\/pt\/category\/lugares\/"},{"@type":"ListItem","position":3,"name":"Bandeira com mapa do pa\u00eds","item":"https:\/\/coloringonly.com\/pt\/lugares\/pagina-de-coloracao-de-mapa-de-pais-com-bandeira\/"},{"@type":"ListItem","position":4,"name":"Bandeira e mapa do Canad\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/.\/canada-flag-and-map-coloring-page-2.png'><img decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/canada-flag-and-map-coloring-page-2.png\" class=\"attachment-medium size-medium\" alt=\"Bandeira do Canad\u00e1 e Mapa para Colorir\" \/><\/a><\/p>\n<p>Bandeira do Canad\u00e1 e Mapa para Colorir<\/p>\n"},"caption":{"rendered":"<p>Bandeira do Canad\u00e1 e Mapa para Colorir<\/p>\n"},"alt_text":"Bandeira do Canad\u00e1 e Mapa para Colorir","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":800,"file":".\/canada-flag-and-map-coloring-page-2.png","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":300197,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/canada-flag-and-map-coloring-page-2.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/300203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=300203"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":300197,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/300197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}