{"id":301598,"date":"2022-09-17T01:31:23","date_gmt":"2022-09-17T01:31:23","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Jolene-Cujoh-coloring-page.jpg"},"modified":"2024-08-25T16:07:48","modified_gmt":"2024-08-25T16:07:48","slug":"jolene-cujoh-coloring-page-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/anime-pt\/jojos-bizarro-aventura\/attachment\/jolene-cujoh-coloring-page-2\/","title":{"rendered":"Jolene Cujoh"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-301598","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jolene Cujoh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/anime-pt\/jojos-bizarro-aventura\/attachment\/jolene-cujoh-coloring-page-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-25T16:07:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/Jolene-Cujoh-coloring-page.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"957\" \/>\n\t<meta property=\"og:image:height\" content=\"747\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jolene Cujoh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/anime-pt\/jojos-bizarro-aventura\/attachment\/jolene-cujoh-coloring-page-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-25T16:07:48+00:00","og_image":[{"width":957,"height":747,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/Jolene-Cujoh-coloring-page.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/anime-pt\/jojos-bizarro-aventura\/attachment\/jolene-cujoh-coloring-page-2\/","url":"https:\/\/coloringonly.com\/pt\/anime-pt\/jojos-bizarro-aventura\/attachment\/jolene-cujoh-coloring-page-2\/","name":"Jolene Cujoh Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2022-09-17T01:31:23+00:00","dateModified":"2024-08-25T16:07:48+00:00","description":"Free printable Jolene Cujoh coloring page. You can download Jolene Cujoh coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/anime-pt\/jojos-bizarro-aventura\/attachment\/jolene-cujoh-coloring-page-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/anime-pt\/jojos-bizarro-aventura\/attachment\/jolene-cujoh-coloring-page-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/anime-pt\/jojos-bizarro-aventura\/attachment\/jolene-cujoh-coloring-page-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Anime","item":"https:\/\/coloringonly.com\/pt\/category\/anime-pt\/"},{"@type":"ListItem","position":3,"name":"A Bizarra Aventura de JoJo","item":"https:\/\/coloringonly.com\/pt\/anime-pt\/jojos-bizarro-aventura\/"},{"@type":"ListItem","position":4,"name":"Jolene Cujoh"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/Jolene-Cujoh-coloring-page.jpg'><img decoding=\"async\" width=\"957\" height=\"747\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/Jolene-Cujoh-coloring-page.jpg\" class=\"attachment-medium size-medium\" alt=\"A Bizarra Aventura de JoJo\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":957,"height":747,"file":"Jolene-Cujoh-coloring-page.jpg","sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":70637},"post":301584,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Jolene-Cujoh-coloring-page.jpg","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/301598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=301598"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":301584,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/301584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}