{"id":304198,"date":"2024-08-25T16:46:11","date_gmt":"2024-08-25T16:46:11","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/interactive-mexican-independence-day-coloring-sheet.png"},"modified":"2024-08-27T11:38:19","modified_gmt":"2024-08-27T11:38:19","slug":"dia-da-independencia-do-mexico-interativo","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/ferias\/pagina-para-colorir-imprimivel-do-dia-da-independencia-mexicana\/attachment\/dia-da-independencia-do-mexico-interativo\/","title":{"rendered":"Dia da Independ\u00eancia do M\u00e9xico interativo"},"author":34,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-304198","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dia da Independ\u00eancia do M\u00e9xico interativo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/ferias\/pagina-para-colorir-imprimivel-do-dia-da-independencia-mexicana\/attachment\/dia-da-independencia-do-mexico-interativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-27T11:38:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/interactive-mexican-independence-day-coloring-sheet.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia da Independ\u00eancia do M\u00e9xico interativo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/ferias\/pagina-para-colorir-imprimivel-do-dia-da-independencia-mexicana\/attachment\/dia-da-independencia-do-mexico-interativo\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2024-08-27T11:38:19+00:00","og_image":[{"width":600,"height":800,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/interactive-mexican-independence-day-coloring-sheet.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/ferias\/pagina-para-colorir-imprimivel-do-dia-da-independencia-mexicana\/attachment\/dia-da-independencia-do-mexico-interativo\/","url":"https:\/\/coloringonly.com\/pt\/ferias\/pagina-para-colorir-imprimivel-do-dia-da-independencia-mexicana\/attachment\/dia-da-independencia-do-mexico-interativo\/","name":"Dia da Independ\u00eancia do M\u00e9xico interativo Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2024-08-25T16:46:11+00:00","dateModified":"2024-08-27T11:38:19+00:00","description":"Free printable Dia da Independ\u00eancia do M\u00e9xico interativo coloring page. You can download Dia da Independ\u00eancia do M\u00e9xico interativo coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/ferias\/pagina-para-colorir-imprimivel-do-dia-da-independencia-mexicana\/attachment\/dia-da-independencia-do-mexico-interativo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/ferias\/pagina-para-colorir-imprimivel-do-dia-da-independencia-mexicana\/attachment\/dia-da-independencia-do-mexico-interativo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/ferias\/pagina-para-colorir-imprimivel-do-dia-da-independencia-mexicana\/attachment\/dia-da-independencia-do-mexico-interativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"F\u00e9rias","item":"https:\/\/coloringonly.com\/pt\/category\/ferias\/"},{"@type":"ListItem","position":3,"name":"Dia da Independ\u00eancia do M\u00e9xico","item":"https:\/\/coloringonly.com\/pt\/holidays\/mexican-independence-day-printable-coloring-page\/"},{"@type":"ListItem","position":4,"name":"Dia da Independ\u00eancia do M\u00e9xico interativo"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/.\/interactive-mexican-independence-day-coloring-sheet.png'><img decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/interactive-mexican-independence-day-coloring-sheet.png\" class=\"attachment-medium size-medium\" alt=\"Folha de colorir interativa do Dia da Independ\u00eancia do M\u00e9xico\" srcset=\"https:\/\/coloringonly.com\/images\/imgcolor\/interactive-mexican-independence-day-coloring-sheet.png 600w, https:\/\/coloringonly.com\/images\/imgcolor\/interactive-mexican-independence-day-coloring-sheet-150x200.png 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Folha de colorir interativa do Dia da Independ\u00eancia do M\u00e9xico  <\/p>\n"},"caption":{"rendered":"<p>Folha de colorir interativa do Dia da Independ\u00eancia do M\u00e9xico  <\/p>\n"},"alt_text":"Folha de colorir interativa do Dia da Independ\u00eancia do M\u00e9xico","media_type":"image","mime_type":"image\/png","media_details":{"width":600,"height":800,"file":".\/interactive-mexican-independence-day-coloring-sheet.png","filesize":96738,"sizes":{"web-stories-publisher-logo":{"file":"interactive-mexican-independence-day-coloring-sheet-96x96.png","width":96,"height":96,"filesize":5295,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/interactive-mexican-independence-day-coloring-sheet-96x96.png"},"web-stories-thumbnail":{"file":"interactive-mexican-independence-day-coloring-sheet-150x200.png","width":150,"height":200,"filesize":14050,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/interactive-mexican-independence-day-coloring-sheet-150x200.png"},"full":{"file":"interactive-mexican-independence-day-coloring-sheet.png","width":600,"height":800,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/interactive-mexican-independence-day-coloring-sheet.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":308754,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/interactive-mexican-independence-day-coloring-sheet.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/304198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=304198"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":308754,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/308754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}