{"id":318931,"date":"2024-10-31T08:03:08","date_gmt":"2024-10-31T08:03:08","guid":{"rendered":"https:\/\/coloringonly.com\/images\/imgcolor\/Halloween-frog-in-cauldron-coloring-page-cute-01.png"},"modified":"2025-01-16T21:03:27","modified_gmt":"2025-01-16T21:03:27","slug":"halloween-frog-in-cauldron-coloring-page-cute-01-2","status":"inherit","type":"attachment","link":"https:\/\/coloringonly.com\/pt\/ferias\/easy-cute-halloween-coloring-pages\/attachment\/halloween-frog-in-cauldron-coloring-page-cute-01-2\/","title":{"rendered":"Sapo fofo de Halloween no caldeir\u00e3o"},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-318931","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sapo fofo de Halloween no caldeir\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coloringonly.com\/pt\/ferias\/easy-cute-halloween-coloring-pages\/attachment\/halloween-frog-in-cauldron-coloring-page-cute-01-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Coloring Pages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Coloring-Only-104926520903807\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T21:03:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coloringonly.com\/images\/imgcolor\/.\/halloween-cute-frog-in-cauldron-coloring-page.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ColoringO\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sapo fofo de Halloween no caldeir\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_url":"https:\/\/coloringonly.com\/pt\/ferias\/easy-cute-halloween-coloring-pages\/attachment\/halloween-frog-in-cauldron-coloring-page-cute-01-2\/","og_site_name":"Coloring Pages","article_publisher":"https:\/\/www.facebook.com\/Coloring-Only-104926520903807","article_modified_time":"2025-01-16T21:03:27+00:00","og_image":[{"width":800,"height":1000,"url":"https:\/\/coloringonly.com\/images\/imgcolor\/.\/halloween-cute-frog-in-cauldron-coloring-page.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ColoringO","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/coloringonly.com\/pt\/ferias\/easy-cute-halloween-coloring-pages\/attachment\/halloween-frog-in-cauldron-coloring-page-cute-01-2\/","url":"https:\/\/coloringonly.com\/pt\/ferias\/easy-cute-halloween-coloring-pages\/attachment\/halloween-frog-in-cauldron-coloring-page-cute-01-2\/","name":"Sapo fofo de Halloween no caldeir\u00e3o Coloring Page - Free Printable Coloring Pages for Kids","isPartOf":{"@id":"https:\/\/coloringonly.com\/pt\/#website"},"datePublished":"2024-10-31T08:03:08+00:00","dateModified":"2025-01-16T21:03:27+00:00","description":"Free printable Sapo fofo de Halloween no caldeir\u00e3o coloring page. You can download Sapo fofo de Halloween no caldeir\u00e3o coloring page for free on ColoringOnly.com.","breadcrumb":{"@id":"https:\/\/coloringonly.com\/pt\/ferias\/easy-cute-halloween-coloring-pages\/attachment\/halloween-frog-in-cauldron-coloring-page-cute-01-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coloringonly.com\/pt\/ferias\/easy-cute-halloween-coloring-pages\/attachment\/halloween-frog-in-cauldron-coloring-page-cute-01-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/coloringonly.com\/pt\/ferias\/easy-cute-halloween-coloring-pages\/attachment\/halloween-frog-in-cauldron-coloring-page-cute-01-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coloringonly.com\/pt\/"},{"@type":"ListItem","position":2,"name":"F\u00e9rias","item":"https:\/\/coloringonly.com\/pt\/category\/ferias\/"},{"@type":"ListItem","position":3,"name":"Dia das Bruxas F\u00e1cil e Fofo","item":"https:\/\/coloringonly.com\/pt\/ferias\/easy-cute-halloween-coloring-pages\/"},{"@type":"ListItem","position":4,"name":"Sapo fofo de Halloween no caldeir\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/coloringonly.com\/pt\/#website","url":"https:\/\/coloringonly.com\/pt\/","name":"Coloring Pages","description":"Free printable coloring pages for kids","publisher":{"@id":"https:\/\/coloringonly.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coloringonly.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coloringonly.com\/pt\/#organization","name":"Coloring pages","url":"https:\/\/coloringonly.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","contentUrl":"https:\/\/coloringonly.com\/images\/imgcolor\/logo2.png","width":117,"height":79,"caption":"Coloring pages"},"image":{"@id":"https:\/\/coloringonly.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Coloring-Only-104926520903807","https:\/\/x.com\/ColoringO"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/coloringonly.com\/images\/imgcolor\/halloween-cute-frog-in-cauldron-coloring-page.png'><img decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/coloringonly.com\/images\/imgcolor\/halloween-cute-frog-in-cauldron-coloring-page.png\" class=\"attachment-medium size-medium\" alt=\"Desenho de Sapo fofo de Halloween no caldeir\u00e3o para colorir\" srcset=\"https:\/\/coloringonly.com\/images\/imgcolor\/halloween-cute-frog-in-cauldron-coloring-page.png 800w, https:\/\/coloringonly.com\/images\/imgcolor\/Halloween-frog-in-cauldron-coloring-page-cute-01-768x960.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Desenho de Sapo fofo de Halloween no caldeir\u00e3o para colorir<\/p>\n"},"caption":{"rendered":"<p>Desenho de Sapo fofo de Halloween no caldeir\u00e3o para colorir<\/p>\n"},"alt_text":"Desenho de Sapo fofo de Halloween no caldeir\u00e3o para colorir","media_type":"image","mime_type":"image\/png","media_details":{"width":800,"height":1000,"file":"halloween-cute-frog-in-cauldron-coloring-page.png","filesize":30726,"sizes":{"medium_large":{"file":"Halloween-frog-in-cauldron-coloring-page-cute-01-768x960.png","width":768,"height":960,"filesize":34465,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/Halloween-frog-in-cauldron-coloring-page-cute-01-768x960.png"},"full":{"file":"halloween-cute-frog-in-cauldron-coloring-page.png","width":800,"height":1000,"mime_type":"image\/png","source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/halloween-cute-frog-in-cauldron-coloring-page.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":327352,"source_url":"https:\/\/coloringonly.com\/images\/imgcolor\/halloween-cute-frog-in-cauldron-coloring-page.png","_links":{"self":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media\/318931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/comments?post=318931"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":327352,"href":"https:\/\/coloringonly.com\/pt\/wp-json\/wp\/v2\/posts\/327352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}